{"id":14114,"date":"2026-05-13T07:43:23","date_gmt":"2026-05-13T07:43:23","guid":{"rendered":"https:\/\/viqtor.eu\/simplification-des-regles-numeriques-europeennes-a-quoi-peut-on-sattendre\/"},"modified":"2026-05-13T07:43:23","modified_gmt":"2026-05-13T07:43:23","slug":"simplification-des-regles-numeriques-europeennes-a-quoi-peut-on-sattendre","status":"publish","type":"post","link":"https:\/\/viqtor.eu\/pt\/simplification-des-regles-numeriques-europeennes-a-quoi-peut-on-sattendre\/","title":{"rendered":"Simplifica\u00e7\u00e3o das regras digitais europeias: o que podemos esperar?"},"content":{"rendered":"<h4><strong>Veille Juridique n\u00b089 \u2013 novembre 2025.&nbsp; <\/strong><\/h4>\n<h4><strong>&nbsp;<\/strong><\/h4>\n<h4><strong><u>Simplifica\u00e7\u00e3o das regras digitais europeias: o que podemos esperar?<\/u><\/strong><\/h4>\n<p>Jusqu\u2019o\u00f9 la Commission europ\u00e9enne ira-t-elle dans sa volont\u00e9 de simplifier le cadre l\u00e9gislatif europ\u00e9en ?<\/p>\n<p>Depuis la publication du rapport Draghi en septembre 2024, et dans un contexte \u00e9conomique international chahut\u00e9, l\u2019ex\u00e9cutif europ\u00e9en multiplie les mesures en faveur de l\u2019industrie.<\/p>\n<p>La publication r\u00e9cente du paquet \u00ab Digital Omnibus \u00bb entend ainsi rassurer le secteur priv\u00e9 quant aux contraintes l\u00e9gales dans le secteur du num\u00e9rique, au grand dam de la soci\u00e9t\u00e9 civile qui craint une \u00e9rosion sans pr\u00e9c\u00e9dent des droits fondamentaux.<\/p>\n<p>La Commission a officiellement publi\u00e9 le 19 novembre deux propositions, le \u00ab Digital Omnibus \u00bb et le \u00ab Digital Omnibus sur l&rsquo;IA \u00bb et lanc\u00e9 un bilan de qualification num\u00e9rique.<\/p>\n<p>La proposition relative au num\u00e9rique apporte des modifications tant au RGPD qu\u2019au r\u00e8glement sur l\u2019IA et \u00e0 la directive ePrivacy. Le texte est dense, en voici quelques grandes lignes.<\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li><strong>En ce qui concerne la directive ePrivacy, <\/strong><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p style=\"padding-left: 40px;\">La Commission propose notamment des modifications au r\u00e9gime des cookies. L&rsquo;objectif est de r\u00e9duire le nombre d&rsquo;apparitions des banni\u00e8res et de permettre aux utilisateurs de donner leur consentement en un seul clic et d&rsquo;enregistrer leurs pr\u00e9f\u00e9rences via les param\u00e8tres centraux des navigateurs et des syst\u00e8mes d&rsquo;exploitation. Cette disposition figure parmi les moins contest\u00e9es.<\/p>\n<p style=\"padding-left: 40px;\">Le texte pr\u00e9voit aussi une interface de signalement unifi\u00e9e permettant aux entreprises de satisfaire \u00e0 toutes leurs obligations de notification des incidents via un portail s\u00e9curis\u00e9 unique, dans l\u2019objectif de simplifier les obligations concurrentes de la directive NIS2, du RGPD et du r\u00e8glement sur la r\u00e9silience op\u00e9rationnelle num\u00e9rique.<\/p>\n<p style=\"padding-left: 40px;\">Un all\u00e8gement des obligations l\u00e9gales est pr\u00e9vu pour les PMEs et les entreprises \u00e0 faible et moyenne capitalisation concernant la documentation, les sanctions, et les r\u00e8gles de commutation cloud.<\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li><strong>Au sujet du RGPD, <\/strong><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p style=\"padding-left: 40px;\">La proposition restreint la d\u00e9finition des donn\u00e9es \u00e0 caract\u00e8re personnel en introduisant une approche subjective de l\u2019identifiabilit\u00e9 des donn\u00e9es, qui pourrait exclure du champ d\u2019application du r\u00e8glement certaines donn\u00e9es pseudonymes ou num\u00e9ros d&rsquo;identification.<\/p>\n<p style=\"padding-left: 40px;\">La d\u00e9finition des donn\u00e9es sensibles serait modifi\u00e9e pour ne concerner que celles qui r\u00e9v\u00e8lent \u00ab directement \u00bb des informations concernant la sant\u00e9, l\u2019origine raciale, etc., au risque d\u2019exclure celles qui pourraient \u00eatre d\u00e9duites par un algorithme par exemple.<\/p>\n<p style=\"padding-left: 40px;\">La proposition entend \u00e9galement restreindre le droit des individus de demander l&rsquo;acc\u00e8s \u00e0 leurs donn\u00e9es uniquement \u00e0 des \u00ab fins de protection des donn\u00e9es \u00bb.<\/p>\n<p style=\"padding-left: 40px;\">Une nouvelle d\u00e9finition de la \u00ab recherche scientifique \u00bb pourrait en outre entra\u00eener des exemptions de grande envergure au RGPD b\u00e9n\u00e9ficiant au secteur priv\u00e9 : \u00ab toute recherche susceptible de soutenir l&rsquo;innovation, telle que le d\u00e9veloppement technologique et la d\u00e9monstration \u00bb pourrait ainsi \u00eatre dispens\u00e9e des obligations d\u2019information et de limitation de finalit\u00e9.<\/p>\n<p>La proposition comprend des modifications facilitant la prise de d\u00e9cision sur une base automatis\u00e9e, et permettant l\u2019utilisation de donn\u00e9es personnelles pour former et exploiter les syst\u00e8mes d&rsquo;IA sur la base de l\u2019int\u00e9r\u00eat l\u00e9gitime.<\/p>\n<p>Le texte pr\u00e9voit \u00e9galement une p\u00e9riode transitoire de six mois pour l&rsquo;article 50(2) du r\u00e8glement sur l&rsquo;IA (obligations de transparence).<\/p>\n<p>Le paquet omnibus num\u00e9rique reste ouvert aux commentaires pendant une p\u00e9riode de huit semaines, prolong\u00e9e chaque jour jusqu&rsquo;\u00e0 ce que la proposition soit disponible dans toutes les langues de l&rsquo;UE, actuellement jusqu&rsquo;au 29 janvier 2026.<\/p>\n<p>La proposition suivra ensuite les proc\u00e9dures l\u00e9gislatives ordinaires de l&rsquo;UE au Parlement europ\u00e9en et au Conseil, o\u00f9 elles feront certainement l&rsquo;objet de vifs d\u00e9bats.<\/p>\n<p>En ce qui concerne plus pr\u00e9cis\u00e9ment le RGPD, certains pays sont ouverts \u00e0 un examen des propositions de la Commission, alors que d\u2019autres, dont la Slov\u00e9nie, l\u2019Estonie ou l\u2019Autriche, ont d\u00e9j\u00e0 fait savoir qu&rsquo;\u00e0 leurs yeux, le RGPD ne \u00ab n\u00e9cessite aucune modification suppl\u00e9mentaire pour le moment \u00bb.<\/p>\n<p>Le processus inclura \u00e9galement les avis du Comit\u00e9 europ\u00e9en de la protection des donn\u00e9es et du Contr\u00f4leur europ\u00e9en de la protection des donn\u00e9es, deux positions qui, bien que non-contraignantes, devraient influencer la suite des discussions.<\/p>\n<h4>&nbsp;<\/h4>\n<h4><strong><img decoding=\"async\" src=\"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/05\/france_1778143307040.jpg\" alt=\"\" width=\"140\" height=\"94\"><\/strong><\/h4>\n<p><strong>Apr\u00e8s un premier rapport \u00e9valuant si les Fran\u00e7ais \u00e9taient pr\u00eats \u00e0 payer pour des services en ligne sans publicit\u00e9 cibl\u00e9e, la CNIL a publi\u00e9 le 17 novembre un deuxi\u00e8me volet concernant l\u2019attitude des Fran\u00e7ais au regard de la mon\u00e9tisation de leurs donn\u00e9es. <\/strong><\/p>\n<p>65 % des r\u00e9pondants se disent ainsi pr\u00eats \u00e0 vendre leurs donn\u00e9es. La valorisation la plus fr\u00e9quente est entre 10 \u00e0 30 euros mensuels, privil\u00e9gi\u00e9e par 28 % de ces r\u00e9pondants.<\/p>\n<p>En revanche, 35 % des individus ne souhaitent pas vendre leurs donn\u00e9es, quel qu\u2019en soit le prix, exprimant un rejet de principe de la mon\u00e9tisation des donn\u00e9es personnelles.<\/p>\n<p>La CNIL rappelle \u00e0 cet \u00e9gard que, s\u2019il est possible de c\u00e9der un droit d\u2019usage sur ses donn\u00e9es, \u00ab une pratique de \u00ab mon\u00e9tisation \u00bb de ses donn\u00e9es personnelles, au sens de c\u00e9der un droit de propri\u00e9t\u00e9 sur celles-ci, n\u2019est pas possible dans le cadre l\u00e9gal actuel puisqu\u2019on ne saurait renoncer \u00e0 ses droits sur ses donn\u00e9es. \u00bb<\/p>\n<p>Le 20 novembre 2025, la CNIL a sanctionn\u00e9 la soci\u00e9t\u00e9 fran\u00e7aise Les publications Conde Nast d\u2019une amende de 750 000 euros pour le non-respect des r\u00e8gles applicables en mati\u00e8re de cookies, d\u00e9pos\u00e9s sur le terminal des utilisateurs se rendant sur le site \u00ab vanityfair.fr \u00bb.<\/p>\n<p>La soci\u00e9t\u00e9 avait d\u00e9j\u00e0 fait l\u2019objet d\u2018une mise en demeure \u00e0 la suite d\u2019une plainte de l\u2019association Noyb en 2019, sans se mettre en conformit\u00e9.<\/p>\n<p>L\u2019amende tient compte du manque de r\u00e9action de la soci\u00e9t\u00e9 ainsi que du nombre de personnes concern\u00e9es et des diff\u00e9rents manquements : absence de recueil du consentement, d\u00e9faut d\u2019information des utilisateurs et d\u00e9faillance des m\u00e9canismes de refus et de retrait de consentement.<\/p>\n<p>La CNIL a \u00e9galement impos\u00e9 le 27 novembre 2025 une amende de 1,5 million d\u2019euros \u00e0 la soci\u00e9t\u00e9 American Express carte France pour le non-respect des r\u00e8gles applicables en mati\u00e8re de cookies.<\/p>\n<p><strong>L\u2019ANSSI a publi\u00e9 le 26 novembre un rapport concernant l\u2019\u00e9tat de la menace pesant sur les t\u00e9l\u00e9phones mobiles. <\/strong><\/p>\n<p>Le rapport pointe l\u2019exploitation par les attaquants de vuln\u00e9rabilit\u00e9s pouvant cibler les r\u00e9seaux, le syst\u00e8me d\u2019exploitation ou les applications, et identifie une menace sp\u00e9cifique : les op\u00e9rations d\u2019espionnage et de surveillance men\u00e9es par des acteurs \u00e9tatiques.<\/p>\n<p>Les t\u00e9l\u00e9phones mobiles sont aussi une cible de choix pour les cybercriminels, qui, en les compromettant, parviennent notamment \u00e0 d\u00e9tourner de l\u2019argent de leurs victimes.<\/p>\n<p>Les t\u00e9l\u00e9phones mobiles sont aussi d\u00e9tourn\u00e9s pour de la surveillance priv\u00e9e ou des op\u00e9rations de d\u00e9stabilisation.<\/p>\n<p>Le rapport fournit \u00e9galement des recommandations de s\u00e9curit\u00e9 \u00e0 destination des utilisateurs.<\/p>\n<p>Parmi celles-ci, \u00e9teindre r\u00e9guli\u00e8rement puis rallumer son t\u00e9l\u00e9phone sans utiliser la fonctionnalit\u00e9 de red\u00e9marrage, ne pas cliquer sur des liens ou ouvrir des fichiers pr\u00e9sents dans des messages non sollicit\u00e9s, \u00eatre vigilant lors de l\u2019ouverture de liens transmis via des QR codes, appliquer les mises \u00e0 jour du syst\u00e8me d\u2019exploitation, d\u00e9sactiver les interfaces Wifi et Bluetooth lorsqu\u2019elles ne sont pas utilis\u00e9es, et \u00e9viter de se connecter aux r\u00e9seaux de Wifi publics.<\/p>\n<h4><strong>&nbsp;<\/strong><\/h4>\n<h4><strong><img decoding=\"async\" src=\"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/05\/Europe_1778143264083.jpg\" alt=\"\" width=\"140\" height=\"93\"><\/strong><\/h4>\n<h4><strong>Institui\u00e7\u00f5es e \u00f3rg\u00e3os europeus <\/strong><\/h4>\n<p>Le 26 novembre, les repr\u00e9sentants des \u00c9tats membres de l&rsquo;UE se sont mis d&rsquo;accord sur la position du Conseil concernant le r\u00e8glement visant \u00e0 pr\u00e9venir et \u00e0 combattre les abus sexuels commis sur des enfants.<\/p>\n<p>Le texte entend imposer aux entreprises du secteur num\u00e9rique l&rsquo;obligation de pr\u00e9venir la diffusion de contenus \u00e0 caract\u00e8re p\u00e9dopornographique et la sollicitation d&rsquo;enfants.<\/p>\n<p>Les autorit\u00e9s nationales comp\u00e9tentes auront le pouvoir d&rsquo;obliger les entreprises \u00e0 supprimer et \u00e0 bloquer l&rsquo;acc\u00e8s \u00e0 certains contenus ou, dans le cas des moteurs de recherche, \u00e0 supprimer certains r\u00e9sultats de recherche.<\/p>\n<p>Le r\u00e8glement pr\u00e9voit \u00e9galement la cr\u00e9ation d&rsquo;une nouvelle agence europ\u00e9enne, le Centre europ\u00e9en sur la p\u00e9dopornographie, charg\u00e9e d&rsquo;aider les \u00c9tats membres et les fournisseurs de services en ligne \u00e0 mettre en \u0153uvre la loi.<\/p>\n<p>Le Conseil souhaite \u00e9galement rendre permanente une mesure actuellement temporaire qui permet aux entreprises de scanner volontairement leurs services \u00e0 la recherche d&rsquo;abus sexuels sur des enfants.<\/p>\n<p>Bien que moins intrusif que sa pr\u00e9c\u00e9dente version, le texte est toujours consid\u00e9r\u00e9 par ses d\u00e9tracteurs comme une attaque contre le chiffrement de bout en bout et la confidentialit\u00e9 des communications.<\/p>\n<p>Le projet doit encore faire l\u2019objet de discussions lors de trilogues avec la Commission et le Parlement europ\u00e9en.<\/p>\n<p>Le 5 d\u00e9cembre, la Commission europ\u00e9enne a inflig\u00e9 une amende de 120 millions d&rsquo;euros \u00e0 X pour avoir manqu\u00e9 \u00e0 ses obligations de transparence en vertu de la loi sur les services num\u00e9riques (DSA).<\/p>\n<p>Les manquements concernent notamment la conception trompeuse de sa \u00ab validation bleue \u00bb pour les comptes v\u00e9rifi\u00e9s, le manque de transparence de son r\u00e9pertoire publicitaire et le fait de ne pas avoir donn\u00e9 acc\u00e8s aux donn\u00e9es publiques aux chercheurs.<\/p>\n<p>Dans sa d\u00e9cision Russ media du 2 d\u00e9cembre, la Cour de justice de l\u2019Union europ\u00e9enne (CJUE) a consid\u00e9r\u00e9 qu\u2019un \u00e9diteur de place de march\u00e9 est responsable du traitement des annonces publi\u00e9es sur sa plateforme et doit v\u00e9rifier, avant publication, si celles-ci contiennent des donn\u00e9es sensibles et si leur traitement respecte le RGPD.<\/p>\n<p>1\/&nbsp;L\u2019op\u00e9rateur d\u2019une place de march\u00e9 est responsable de traitement des annonces publi\u00e9es&nbsp;: plusieurs \u00e9l\u00e9ments justifient cette qualification pour la CJUE :<\/p>\n<ul style=\"list-style-type: square;\">\n<li>L\u2019annonce n\u2019est accessible en ligne qu\u2019en raison du service fourni par la plateforme.<\/li>\n<li>L&nbsp;\u2019\u00e9diteur poursuit une finalit\u00e9 propre, notamment commerciale et publicitaire, et ne se limite pas \u00e0 une prestation technique.<\/li>\n<li>Il d\u00e9termine des moyens essentiels : pr\u00e9sentation, dur\u00e9e de mise en ligne, rubriques, classement, modalit\u00e9s de diffusion.<\/li>\n<li>Ainsi, l\u2019op\u00e9rateur et l\u2019annonceur sont responsables conjoints du traitement effectu\u00e9 sur les annonces.<\/li>\n<\/ul>\n<p>2\/ En tant que responsable du traitement, l\u2019op\u00e9rateur doit identifier les risques potentiels d\u2019un traitement de donn\u00e9es et impl\u00e9menter les mesures et garanties appropri\u00e9es au risque identifi\u00e9&nbsp;: la CJUE indique que l\u2019op\u00e9rateur doit en amont :<\/p>\n<ul style=\"list-style-type: square;\">\n<li>D\u00e9tecter si une annonce contient des donn\u00e9es sensibles.<\/li>\n<li>V\u00e9rifier si ces donn\u00e9es concerne l\u2019annonceur ou si celui-ci dispose d\u2019une d\u00e9rogation, notamment un consentement explicite de la personne concern\u00e9e.<\/li>\n<li>Refuser la publication si ces conditions ne sont pas r\u00e9unies.<\/li>\n<\/ul>\n<p>Au titre de ses obligations de s\u00e9curit\u00e9, l\u2019op\u00e9rateur doit aussi mettre en place des mesures visant \u00e0 limiter la copie et la reproduction illicite des annonces contenant des donn\u00e9es sensibles.<\/p>\n<p>Le 20 novembre, la CJUE s\u2019est prononc\u00e9e dans l\u2019affaire Policejn\u00ed prezidium sur les pratiques de la police tch\u00e8que consistant \u00e0 collecter et \u00e0 conserver ind\u00e9finiment les donn\u00e9es biom\u00e9triques et g\u00e9n\u00e9tiques de toutes les personnes soup\u00e7onn\u00e9es d&rsquo;avoir commis des infractions intentionnelles.<\/p>\n<p>Il s\u2019agissait de d\u00e9terminer si la directive europ\u00e9enne \u00ab Police \u00bb exige une \u00e9valuation au cas par cas de la n\u00e9cessit\u00e9 de la conservation, si des p\u00e9riodes de conservation ind\u00e9finies sont autoris\u00e9es et quelles garanties juridiques doivent r\u00e9gir le traitement de ces donn\u00e9es sensibles.<\/p>\n<p>La Cour ne constate pas une interdiction de principe mais impose une s\u00e9rie de conditions : le responsable de traitement doit se conformer \u00e0 tous les principes et exigences sp\u00e9cifiques applicables au traitement des donn\u00e9es sensibles, et la l\u00e9gislation nationale doit fixer des d\u00e9lais appropri\u00e9s pour un r\u00e9examen p\u00e9riodique de la stricte n\u00e9cessit\u00e9 de conserver ces donn\u00e9es.<\/p>\n<p>L\u2019Agence europ\u00e9enne des droits fondamentaux a publi\u00e9 le 4 d\u00e9cembre un rapport traitant de la protection des droits fondamentaux lors de l&rsquo;utilisation de l&rsquo;IA dans des domaines \u00e0 haut risque. Il met en \u00e9vidence un manque de sensibilisation aux droits<\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<h4><strong>Not\u00edcias dos pa\u00edses membros da Uni\u00e3o Europeia. <\/strong><\/h4>\n<p>Le Tribunal r\u00e9gional de Vienne pour les affaires civiles a estim\u00e9 qu&rsquo;une action en justice contre un responsable de traitement non \u00e9tabli dans l&rsquo;UE devait \u00eatre signifi\u00e9e \u00e0 ce dernier et non \u00e0 son repr\u00e9sentant dans l\u2019UE.<\/p>\n<p>Une signification au repr\u00e9sentant en vertu de l&rsquo;article 27 du RGPD est insuffisante, sauf si le droit proc\u00e9dural national pr\u00e9voit cette option.<\/p>\n<p>L\u2019APD croate a inflig\u00e9 le 14 novembre une amende administrative d&rsquo;un montant total de 4 500 000,00 EUR \u00e0 un op\u00e9rateur de t\u00e9l\u00e9communications, en sa qualit\u00e9 de responsable du traitement, pour transfert de donn\u00e9es \u00e0 caract\u00e8re personnel vers un pays tiers en violation du RGPD.<\/p>\n<p>Le transfert vers un sous-traitant serbe \u00e9tait effectu\u00e9 sans base l\u00e9gale valide et sans information transparente aux personnes concern\u00e9es, le traitement de copies des cartes d&rsquo;identit\u00e9 et des certificats de casier judiciaire des employ\u00e9s sans base juridique, et en l&rsquo;absence de contr\u00f4les pr\u00e9alables appropri\u00e9s du sous-traitant.<\/p>\n<p>L\u2019universit\u00e9 internationale de Valence en Espagne a \u00e9t\u00e9 condamn\u00e9e \u00e0 une amende de 750 000 \u20ac pour utilisation de la reconnaissance faciale et de l&rsquo;IA pour identifier les participants \u00e0 un examen sans base juridique appropri\u00e9e.<\/p>\n<p>En Espagne \u00e9galement, l\u2019APD a inflig\u00e9 une amende de 30 000 \u20ac \u00e0 une clinique m\u00e9dicale pour avoir enfreint l&rsquo;article 5(1)(f) du RGPD en divulguant les num\u00e9ros de t\u00e9l\u00e9phone et les donn\u00e9es de sant\u00e9 d\u2019environ 90 clients dans un groupe de messagerie Whatsapp sans consentement pr\u00e9alable et sans mesures de confidentialit\u00e9 ad\u00e9quates.<\/p>\n<p>Un tribunal a accord\u00e9 plus de 480 000 000 \u20ac de dommages et int\u00e9r\u00eats \u00e0 87 m\u00e9dias espagnols apr\u00e8s avoir conclu que Meta avait utilis\u00e9 ill\u00e9galement les donn\u00e9es personnelles collect\u00e9es sur ses r\u00e9seaux sociaux pour cr\u00e9er des profils d&rsquo;utilisateurs d\u00e9taill\u00e9s et proposer des publicit\u00e9s personnalis\u00e9es plus efficaces que celles de ses concurrents, obtenant de la sorte un avantage concurrentiel d\u00e9loyal.<\/p>\n<p>Le tribunal a consid\u00e9r\u00e9 que le traitement de donn\u00e9es \u00e0 caract\u00e8re personnel est un facteur concurrentiel cl\u00e9 dans l&rsquo;\u00e9conomie num\u00e9rique et que les violations du RGPD peuvent constituer une concurrence d\u00e9loyale lorsqu&rsquo;elles conf\u00e8rent un avantage significatif.<\/p>\n<p>L\u2019APD italienne a inflig\u00e9 une amende de 32 000 euros \u00e0 la province de Bolzano pour avoir exploit\u00e9 ill\u00e9galement un r\u00e9seau de cam\u00e9ras surveillant les flux de circulation. La province ne disposait d&rsquo;aucune base juridique valable pour le traitement des donn\u00e9es \u00e0 caract\u00e8re personnel, en particulier le traitement des plaques d&rsquo;immatriculation.<\/p>\n<h4><strong>&nbsp;<\/strong><\/h4>\n<h4><img decoding=\"async\" src=\"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/05\/INTERNATIO_1778143183032.jpg\" alt=\"\" width=\"150\" height=\"85\"><\/h4>\n<p>Au Royaume-Uni, 73 universitaires, avocats, experts en protection des donn\u00e9es et organisations non gouvernementales ont r\u00e9clam\u00e9 dans une lettre \u00e0 la Chambre des communes une enqu\u00eate sur l&rsquo;organisme britannique charg\u00e9 de la protection des donn\u00e9es (ICO), apr\u00e8s ce qu&rsquo;ils qualifient d&rsquo;\u00ab effondrement des mesures coercitives \u00bb \u00e0 la suite notamment du scandale de la violation des donn\u00e9es afghanes.<\/p>\n<p>Ils mettent en garde contre des \u00ab d\u00e9faillances structurelles plus profondes \u00bb au-del\u00e0 de cette violation de donn\u00e9es.<\/p>\n<p>Celle-ci avait constitu\u00e9 une fuite particuli\u00e8rement grave d&rsquo;informations concernant des Afghans ayant collabor\u00e9 avec les forces britanniques avant que les talibans ne prennent le contr\u00f4le du pays en ao\u00fbt 2021, mettant en danger la vie des 100 000 personnes dont les noms avaient \u00e9t\u00e9 divulgu\u00e9s par le minist\u00e8re de la d\u00e9fense.<\/p>\n<p>Il est reproch\u00e9 \u00e0 l\u2019ICO de ne pas avoir entam\u00e9 de poursuites formelles contre le minist\u00e8re, malgr\u00e9 des manquements r\u00e9p\u00e9t\u00e9s.&nbsp;<\/p>\n<p>En Argentine, certains tribunaux se sont prononc\u00e9s au cours des derniers mois au sujet de l\u2019utilisation de l\u2019IA dans les plaidoiries et m\u00e9moires des avocats.<\/p>\n<p>Les affaires concernaient des avocats ayant inclus des citations de jurisprudence s\u2019\u00e9tant av\u00e9r\u00e9es fausses ou inexactes en raison d\u2019hallucinations de l\u2019IA.<\/p>\n<p>Tout comme aux Etats-Unis notamment, les tribunaux argentins commencent \u00e0 \u00e9valuer l&rsquo;\u00e9tendue de la responsabilit\u00e9 professionnelle des avocats : m\u00eame lorsqu&rsquo;ils agissent de bonne foi, le fait de pr\u00e9senter des m\u00e9moires qui citent une jurisprudence inexistante porte atteinte aux principes fondamentaux de la profession, notamment l&rsquo;honn\u00eatet\u00e9, la loyaut\u00e9, et la sinc\u00e9rit\u00e9, pr\u00e9vus dans les codes de d\u00e9ontologie des diff\u00e9rentes juridictions argentines.<\/p>\n<p>Dans les affaires sp\u00e9cifiques examin\u00e9es, les tribunaux ont d\u00e9cid\u00e9 de ne pas imposer de sanctions directes aux avocats.<\/p>\n<p>N\u00e9anmoins, ils ont jug\u00e9 opportun d&rsquo;en informer les barreaux locaux pour les sensibiliser aux risques et aux responsabilit\u00e9s li\u00e9s \u00e0 l&rsquo;utilisation de l&rsquo;IA et pour promouvoir un d\u00e9bat plus large sur l&rsquo;utilisation responsable de l&rsquo;IA dans la pratique juridique.<\/p>\n<p>Le gouvernement australien est le dernier en date \u00e0 avoir d\u00e9voil\u00e9 une feuille de route en mati\u00e8re d&rsquo;IA.<\/p>\n<p>Apr\u00e8s avoir envisag\u00e9 une strat\u00e9gie ax\u00e9e sur la s\u00e9curit\u00e9, le gouvernement a finalement choisi de mettre l\u2019accent sur l&rsquo;investissement et l&rsquo;\u00e9conomie.<\/p>\n<p>Plut\u00f4t que d&rsquo;\u00e9tablir des garde-fous obligatoires dans les environnements \u00e0 haut risque, l&rsquo;Australie s\u2019appuiera \u00ab sur les solides cadres juridiques et r\u00e9glementaires existants \u00bb<\/p>\n<p>Le Plan national annonc\u00e9 le 2 d\u00e9cembre vise \u00e0 renforcer la r\u00e9putation de l&rsquo;Australie en tant que lieu d&rsquo;investissement dans l&rsquo;IA, et promeut des objectifs d\u2019utilisation g\u00e9n\u00e9rale de l&rsquo;IA dans le pays, et dans les services publics en particulier.<\/p>\n<p>Il d\u00e9crit \u00e9galement le r\u00f4le de l&rsquo;Institut pour la s\u00e9curit\u00e9 de l&rsquo;IA en mati\u00e8re de tests et partage d\u2019informations sur les capacit\u00e9s, les risques et les dangers de l&rsquo;IA.<\/p>\n<p>En Australie \u00e9galement, les enfants et les adolescents \u00e2g\u00e9s de moins de 16 ans n&rsquo;auront plus le droit d&rsquo;utiliser les r\u00e9seaux sociaux \u00e0 partir du 10 d\u00e9cembre.<\/p>\n<p>Les plateformes sont tenues de mettre en place des mesures de v\u00e9rification de l&rsquo;\u00e2ge.<\/p>\n<p>En cas de non-respect, elles s&rsquo;exposent \u00e0 des amendes pouvant atteindre 28 millions d&rsquo;euros.<\/p>\n<p>Cette interdiction pourrait \u00eatre suivie par d\u2019autres : le Parlement europ\u00e9en a appel\u00e9 le 26 novembre \u00e0 fixer l&rsquo;\u00e2ge minimum \u00e0 16 ans dans toute l&rsquo;Union europ\u00e9enne en ce qui concerne les r\u00e9seaux sociaux, les plateformes de partage de vid\u00e9os et les assistants IA, tout en autorisant l&rsquo;acc\u00e8s aux 13-16 ans avec le consentement parental.<\/p>\n<p>Tout en exprimant leur soutien \u00e0 Commission quant \u00e0 une application europ\u00e9enne de v\u00e9rification de l&rsquo;\u00e2ge et un portefeuille d&rsquo;identit\u00e9 num\u00e9rique europ\u00e9en (eID), les d\u00e9put\u00e9s insistent sur le fait que les syst\u00e8mes de v\u00e9rification de l&rsquo;\u00e2ge doivent pr\u00e9server la vie priv\u00e9e des mineurs.<\/p>\n<p>Aux Etats-Unis, il ne reste plus que deux commissaires sur cinq \u00e0 la Commission f\u00e9d\u00e9rale du commerce (FTC).<\/p>\n<p>Une troisi\u00e8me d\u00e9mission, celle de Melissa Holyoak, a en effet \u00e9t\u00e9 annonc\u00e9e par la FTC 17 novembre 2025.<\/p>\n<p>Cette d\u00e9mission fait suite au licenciement par le pr\u00e9sident Trump de deux commissaires d\u00e9mocrates, ne laissant en place que deux commissaires r\u00e9publicains.<\/p>\n<p>La Cour supr\u00eame a \u00e9t\u00e9 saisie, et sa d\u00e9cision pourrait avoir des implications plus larges sur le pouvoir du pr\u00e9sident sur les agences ind\u00e9pendantes.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n<p>Les voyageurs en provenance de pays tels que la Grande-Bretagne, la France, ou la Cor\u00e9e du Sud, pays \u00e9ligibles au programme d&rsquo;exemption de visa des \u00c9tats-Unis, pourraient bient\u00f4t devoir se soumettre \u00e0 un examen de leurs activit\u00e9s sur les r\u00e9seaux sociaux remontant jusqu&rsquo;\u00e0 cinq ans, selon une proposition d\u00e9pos\u00e9e le 9 d\u00e9cembre par les douanes et la protection des fronti\u00e8res am\u00e9ricaines (CBP).<\/p>\n<p>Le CBP pr\u00e9voit \u00e9galement de demander aux candidats une longue liste de donn\u00e9es personnelles incluant leurs adresses \u00e9lectroniques des dix derni\u00e8res ann\u00e9es, ainsi que les noms, dates de naissance, lieux de r\u00e9sidence et lieux de naissance de leurs parents, conjoints, fr\u00e8res, s\u0153urs et enfants.<\/p>\n<p>Le 13 novembre 2025, le minist\u00e8re indien de l&rsquo;\u00c9lectronique et des Technologies de l&rsquo;information a promulgu\u00e9 les r\u00e8gles de mise en \u0153uvre de la loi de 2023 relatives \u00e0 la protection des donn\u00e9es personnelles num\u00e9riques.<\/p>\n<p>Selon le cabinet Nishith Desai Associates, elles pr\u00e9cisent les exigences de transparence, de consentement et d&rsquo;enregistrement, les obligations de notification en cas de violation des donn\u00e9es, les droits des personnes concern\u00e9es et les d\u00e9tails concernant le Conseil indien de protection des donn\u00e9es.<\/p>","protected":false},"excerpt":{"rendered":"<p>Veille Juridique n\u00b089 \u2013 novembre 2025.&nbsp; &nbsp; Simplification des r\u00e8gles num\u00e9riques europ\u00e9ennes : \u00e0 quoi peut-on s\u2019attendre ? Jusqu\u2019o\u00f9 la Commission europ\u00e9enne ira-t-elle dans sa volont\u00e9 de simplifier le cadre l\u00e9gislatif europ\u00e9en ? Depuis la publication du rapport Draghi en septembre 2024, et dans un contexte \u00e9conomique international chahut\u00e9, l\u2019ex\u00e9cutif europ\u00e9en multiplie les mesures en [&hellip;]<\/p>","protected":false},"author":1,"featured_media":14110,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[35],"tags":[],"class_list":["post-14114","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veille-juridique"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Simplification des r\u00e8gles num\u00e9riques europ\u00e9ennes : \u00e0 quoi peut-on s\u2019attendre ? - Viqtor<\/title>\n<meta name=\"description\" content=\"Simplification des r\u00e8gles num\u00e9riques europ\u00e9ennes : \u00e0 quoi peut-on s\u2019attendre ? - Viqtor\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/viqtor.eu\/pt\/simplification-des-regles-numeriques-europeennes-a-quoi-peut-on-sattendre\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Simplification des r\u00e8gles num\u00e9riques europ\u00e9ennes : \u00e0 quoi peut-on s\u2019attendre ? - Viqtor\" \/>\n<meta property=\"og:description\" content=\"Simplification des r\u00e8gles num\u00e9riques europ\u00e9ennes : \u00e0 quoi peut-on s\u2019attendre ? - Viqtor\" \/>\n<meta property=\"og:url\" content=\"https:\/\/viqtor.eu\/pt\/simplification-des-regles-numeriques-europeennes-a-quoi-peut-on-sattendre\/\" \/>\n<meta property=\"og:site_name\" content=\"Viqtor\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T07:43:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/04\/widget-viqtor.png\" \/>\n<meta name=\"author\" content=\"Bruno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bruno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"17 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/viqtor.eu\/simplification-des-regles-numeriques-europeennes-a-quoi-peut-on-sattendre\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/viqtor.eu\/simplification-des-regles-numeriques-europeennes-a-quoi-peut-on-sattendre\/\"},\"author\":{\"name\":\"Bruno\",\"@id\":\"https:\/\/viqtor.eu\/#\/schema\/person\/3dbd9cc82a28f6cf1695c92eda0099ad\"},\"headline\":\"Simplification des r\u00e8gles num\u00e9riques europ\u00e9ennes : \u00e0 quoi peut-on s\u2019attendre ?\",\"datePublished\":\"2026-05-13T07:43:23+00:00\",\"dateModified\":\"2026-05-13T07:43:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/viqtor.eu\/simplification-des-regles-numeriques-europeennes-a-quoi-peut-on-sattendre\/\"},\"wordCount\":3507,\"publisher\":{\"@id\":\"https:\/\/viqtor.eu\/#organization\"},\"image\":{\"@id\":\"https:\/\/viqtor.eu\/simplification-des-regles-numeriques-europeennes-a-quoi-peut-on-sattendre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/05\/13a903a0-e935-4f30-a53b-c9ea49801877_1778143690044.jpg\",\"articleSection\":[\"Veille juridique\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/viqtor.eu\/simplification-des-regles-numeriques-europeennes-a-quoi-peut-on-sattendre\/\",\"url\":\"https:\/\/viqtor.eu\/simplification-des-regles-numeriques-europeennes-a-quoi-peut-on-sattendre\/\",\"name\":\"Simplification des r\u00e8gles num\u00e9riques europ\u00e9ennes : \u00e0 quoi peut-on s\u2019attendre ? - Viqtor\",\"isPartOf\":{\"@id\":\"https:\/\/viqtor.eu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/viqtor.eu\/simplification-des-regles-numeriques-europeennes-a-quoi-peut-on-sattendre\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/viqtor.eu\/simplification-des-regles-numeriques-europeennes-a-quoi-peut-on-sattendre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/05\/13a903a0-e935-4f30-a53b-c9ea49801877_1778143690044.jpg\",\"datePublished\":\"2026-05-13T07:43:23+00:00\",\"dateModified\":\"2026-05-13T07:43:23+00:00\",\"description\":\"Simplification des r\u00e8gles num\u00e9riques europ\u00e9ennes : \u00e0 quoi peut-on s\u2019attendre ? - Viqtor\",\"breadcrumb\":{\"@id\":\"https:\/\/viqtor.eu\/simplification-des-regles-numeriques-europeennes-a-quoi-peut-on-sattendre\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/viqtor.eu\/simplification-des-regles-numeriques-europeennes-a-quoi-peut-on-sattendre\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/viqtor.eu\/simplification-des-regles-numeriques-europeennes-a-quoi-peut-on-sattendre\/#primaryimage\",\"url\":\"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/05\/13a903a0-e935-4f30-a53b-c9ea49801877_1778143690044.jpg\",\"contentUrl\":\"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/05\/13a903a0-e935-4f30-a53b-c9ea49801877_1778143690044.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/viqtor.eu\/simplification-des-regles-numeriques-europeennes-a-quoi-peut-on-sattendre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/viqtor.eu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Simplification des r\u00e8gles num\u00e9riques europ\u00e9ennes : \u00e0 quoi peut-on s\u2019attendre ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/viqtor.eu\/#website\",\"url\":\"https:\/\/viqtor.eu\/\",\"name\":\"Viqtor\",\"description\":\"Faites du RGPD une opportunit\u00e9 pour votre entreprise.\",\"publisher\":{\"@id\":\"https:\/\/viqtor.eu\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/viqtor.eu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/viqtor.eu\/#organization\",\"name\":\"viqtor.eu\",\"url\":\"https:\/\/viqtor.eu\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/viqtor.eu\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/viqtor.eu\/wp-content\/uploads\/2023\/06\/favicon-noir.svg\",\"contentUrl\":\"https:\/\/viqtor.eu\/wp-content\/uploads\/2023\/06\/favicon-noir.svg\",\"width\":108,\"height\":86,\"caption\":\"viqtor.eu\"},\"image\":{\"@id\":\"https:\/\/viqtor.eu\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/viqtor.eu\/#\/schema\/person\/3dbd9cc82a28f6cf1695c92eda0099ad\",\"name\":\"Bruno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/viqtor.eu\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e5a596f9489de15bfe046e97fb771f63589b601ca7e81ccc2bb9a23582f441a3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e5a596f9489de15bfe046e97fb771f63589b601ca7e81ccc2bb9a23582f441a3?s=96&d=mm&r=g\",\"caption\":\"Bruno\"},\"sameAs\":[\"https:\/\/exciting-panini.13-37-234-21.plesk.page\"],\"url\":\"https:\/\/viqtor.eu\/pt\/author\/mouad_zxum2ebi\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Simplification des r\u00e8gles num\u00e9riques europ\u00e9ennes : \u00e0 quoi peut-on s\u2019attendre ? - Viqtor","description":"Simplification des r\u00e8gles num\u00e9riques europ\u00e9ennes : \u00e0 quoi peut-on s\u2019attendre ? - Viqtor","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/viqtor.eu\/pt\/simplification-des-regles-numeriques-europeennes-a-quoi-peut-on-sattendre\/","og_locale":"pt_PT","og_type":"article","og_title":"Simplification des r\u00e8gles num\u00e9riques europ\u00e9ennes : \u00e0 quoi peut-on s\u2019attendre ? - Viqtor","og_description":"Simplification des r\u00e8gles num\u00e9riques europ\u00e9ennes : \u00e0 quoi peut-on s\u2019attendre ? - Viqtor","og_url":"https:\/\/viqtor.eu\/pt\/simplification-des-regles-numeriques-europeennes-a-quoi-peut-on-sattendre\/","og_site_name":"Viqtor","article_published_time":"2026-05-13T07:43:23+00:00","og_image":[{"url":"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/04\/widget-viqtor.png"}],"author":"Bruno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Bruno","Tempo estimado de leitura":"17 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/viqtor.eu\/simplification-des-regles-numeriques-europeennes-a-quoi-peut-on-sattendre\/#article","isPartOf":{"@id":"https:\/\/viqtor.eu\/simplification-des-regles-numeriques-europeennes-a-quoi-peut-on-sattendre\/"},"author":{"name":"Bruno","@id":"https:\/\/viqtor.eu\/#\/schema\/person\/3dbd9cc82a28f6cf1695c92eda0099ad"},"headline":"Simplification des r\u00e8gles num\u00e9riques europ\u00e9ennes : \u00e0 quoi peut-on s\u2019attendre ?","datePublished":"2026-05-13T07:43:23+00:00","dateModified":"2026-05-13T07:43:23+00:00","mainEntityOfPage":{"@id":"https:\/\/viqtor.eu\/simplification-des-regles-numeriques-europeennes-a-quoi-peut-on-sattendre\/"},"wordCount":3507,"publisher":{"@id":"https:\/\/viqtor.eu\/#organization"},"image":{"@id":"https:\/\/viqtor.eu\/simplification-des-regles-numeriques-europeennes-a-quoi-peut-on-sattendre\/#primaryimage"},"thumbnailUrl":"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/05\/13a903a0-e935-4f30-a53b-c9ea49801877_1778143690044.jpg","articleSection":["Veille juridique"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/viqtor.eu\/simplification-des-regles-numeriques-europeennes-a-quoi-peut-on-sattendre\/","url":"https:\/\/viqtor.eu\/simplification-des-regles-numeriques-europeennes-a-quoi-peut-on-sattendre\/","name":"Simplification des r\u00e8gles num\u00e9riques europ\u00e9ennes : \u00e0 quoi peut-on s\u2019attendre ? - Viqtor","isPartOf":{"@id":"https:\/\/viqtor.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/viqtor.eu\/simplification-des-regles-numeriques-europeennes-a-quoi-peut-on-sattendre\/#primaryimage"},"image":{"@id":"https:\/\/viqtor.eu\/simplification-des-regles-numeriques-europeennes-a-quoi-peut-on-sattendre\/#primaryimage"},"thumbnailUrl":"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/05\/13a903a0-e935-4f30-a53b-c9ea49801877_1778143690044.jpg","datePublished":"2026-05-13T07:43:23+00:00","dateModified":"2026-05-13T07:43:23+00:00","description":"Simplification des r\u00e8gles num\u00e9riques europ\u00e9ennes : \u00e0 quoi peut-on s\u2019attendre ? - Viqtor","breadcrumb":{"@id":"https:\/\/viqtor.eu\/simplification-des-regles-numeriques-europeennes-a-quoi-peut-on-sattendre\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/viqtor.eu\/simplification-des-regles-numeriques-europeennes-a-quoi-peut-on-sattendre\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/viqtor.eu\/simplification-des-regles-numeriques-europeennes-a-quoi-peut-on-sattendre\/#primaryimage","url":"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/05\/13a903a0-e935-4f30-a53b-c9ea49801877_1778143690044.jpg","contentUrl":"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/05\/13a903a0-e935-4f30-a53b-c9ea49801877_1778143690044.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/viqtor.eu\/simplification-des-regles-numeriques-europeennes-a-quoi-peut-on-sattendre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/viqtor.eu\/"},{"@type":"ListItem","position":2,"name":"Simplification des r\u00e8gles num\u00e9riques europ\u00e9ennes : \u00e0 quoi peut-on s\u2019attendre ?"}]},{"@type":"WebSite","@id":"https:\/\/viqtor.eu\/#website","url":"https:\/\/viqtor.eu\/","name":"Viqtor","description":"Faites du RGPD une opportunit\u00e9 pour votre entreprise.","publisher":{"@id":"https:\/\/viqtor.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/viqtor.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/viqtor.eu\/#organization","name":"viqtor.eu","url":"https:\/\/viqtor.eu\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/viqtor.eu\/#\/schema\/logo\/image\/","url":"https:\/\/viqtor.eu\/wp-content\/uploads\/2023\/06\/favicon-noir.svg","contentUrl":"https:\/\/viqtor.eu\/wp-content\/uploads\/2023\/06\/favicon-noir.svg","width":108,"height":86,"caption":"viqtor.eu"},"image":{"@id":"https:\/\/viqtor.eu\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/viqtor.eu\/#\/schema\/person\/3dbd9cc82a28f6cf1695c92eda0099ad","name":"Bruno","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/viqtor.eu\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e5a596f9489de15bfe046e97fb771f63589b601ca7e81ccc2bb9a23582f441a3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e5a596f9489de15bfe046e97fb771f63589b601ca7e81ccc2bb9a23582f441a3?s=96&d=mm&r=g","caption":"Bruno"},"sameAs":["https:\/\/exciting-panini.13-37-234-21.plesk.page"],"url":"https:\/\/viqtor.eu\/pt\/author\/mouad_zxum2ebi\/"}]}},"_links":{"self":[{"href":"https:\/\/viqtor.eu\/pt\/wp-json\/wp\/v2\/posts\/14114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/viqtor.eu\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/viqtor.eu\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/viqtor.eu\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/viqtor.eu\/pt\/wp-json\/wp\/v2\/comments?post=14114"}],"version-history":[{"count":0,"href":"https:\/\/viqtor.eu\/pt\/wp-json\/wp\/v2\/posts\/14114\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/viqtor.eu\/pt\/wp-json\/wp\/v2\/media\/14110"}],"wp:attachment":[{"href":"https:\/\/viqtor.eu\/pt\/wp-json\/wp\/v2\/media?parent=14114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/viqtor.eu\/pt\/wp-json\/wp\/v2\/categories?post=14114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/viqtor.eu\/pt\/wp-json\/wp\/v2\/tags?post=14114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}