{"id":14109,"date":"2026-05-13T07:42:25","date_gmt":"2026-05-13T07:42:25","guid":{"rendered":"https:\/\/viqtor.eu\/cookies-et-ciblage-des-internautes-etat-des-lieux\/"},"modified":"2026-05-13T07:42:25","modified_gmt":"2026-05-13T07:42:25","slug":"cookies-et-ciblage-des-internautes-etat-des-lieux","status":"publish","type":"post","link":"https:\/\/viqtor.eu\/et\/cookies-et-ciblage-des-internautes-etat-des-lieux\/","title":{"rendered":"K\u00fcpsised ja internetikasutajate sihtimine: praegune olukord"},"content":{"rendered":"<h4><strong>Veille Juridique n\u00b086 \u2013 ao\u00fbt 2025.&nbsp; <\/strong><\/h4>\n<h4>&nbsp;<\/h4>\n<h4><strong><u>Cookies et ciblage des internautes : \u00e9tat des lieux.<\/u><\/strong><\/h4>\n<p>La CNIL a inflig\u00e9 le 1er septembre une amende de 325 millions d&rsquo;euros \u00e0 la soci\u00e9t\u00e9 Google et de 150 millions d&rsquo;euros \u00e0 la filiale irlandaise du groupe Shein, deux montants qui vont sensiblement rehausser la moyenne des sanctions d\u00e9cid\u00e9es par la CNIL ces derniers mois.<\/p>\n<p>Google a \u00e9t\u00e9 sanctionn\u00e9 en raison de l&rsquo;affichage de publicit\u00e9s ins\u00e9r\u00e9es entre les e-mails des utilisateurs de Gmail et du placement de cookies lors de la cr\u00e9ation de comptes Google, sans le consentement valable des utilisateurs fran\u00e7ais.<\/p>\n<p>La CNIL impose en outre \u00e0 Google de supprimer dans les six mois cet affichage de publicit\u00e9s et d\u2019obtenir le consentement valide des utilisateurs pour le placement de cookies publicitaires lors de la cr\u00e9ation d&rsquo;un compte Google, sous peine d\u2019une astreinte de 100 000 euros par jour.&nbsp;<\/p>\n<p>L\u2019amende impos\u00e9e \u00e0 Shein concerne aussi le non-respect des r\u00e8gles applicables aux cookies, plac\u00e9s ici sur les appareils des utilisateurs visitant le site web \u00ab shein.com \u00bb.<\/p>\n<p>Ces amendes importantes s&rsquo;inscrivent dans le cadre des diff\u00e9rentes mesures prises par la Commission pour r\u00e9glementer le suivi et de ciblage des internautes, et publi\u00e9es sur son site internet en 2019.<\/p>\n<p>La CNIL avait d\u00e9j\u00e0 inflig\u00e9 une amende de 150 millions d&rsquo;euros \u00e0 Google en d\u00e9cembre 2021 pour violation de la r\u00e9glementation sur les cookies et une amende de 50 millions d&rsquo;euros en raison du manque de transparence et de clart\u00e9 de sa politique de confidentialit\u00e9 ainsi que de l&rsquo;absence de base juridique pour les publicit\u00e9s personnalis\u00e9es.<\/p>\n<p>Elle a aussi sanctionn\u00e9 r\u00e9cemment la soci\u00e9t\u00e9 Orange pour des pratiques similaires d\u2019envoi de publicit\u00e9s sous la forme de courriels.<\/p>\n<p>Ces d\u00e9cisions nous donnent l\u2019occasion de faire le point sur les pratiques de ciblage des internautes et sur le cadre l\u00e9gal.<\/p>\n<p>Les r\u00e8gles applicables aux cas d\u2019esp\u00e8ce sont sp\u00e9cifiques : la Commission rappelle que les op\u00e9rations li\u00e9es \u00e0 l\u2019utilisation des traceurs et \u00e0 la prospection \u00e9lectronique rel\u00e8vent non pas du RGPD mais d\u2019autres r\u00e8gles : la directive \u00ab ePrivacy \u00bb, transpos\u00e9e aux articles 82 de la loi Informatique et Libert\u00e9s pour les traceurs, et L. 34-5 du CPCE pour la prospection commerciale par voie \u00e9lectronique.<\/p>\n<p>Les pratiques consid\u00e9r\u00e9es comme non-conformes concernent principalement le d\u00e9p\u00f4t de traceurs sans le consentement de l\u2019internaute, mais aussi la pratique, qui se d\u00e9veloppe, de l\u2019utilisation de \u00ab murs de traceurs \u00bb (cookie walls) qui conditionnent l\u2019acc\u00e8s de l\u2019internaute \u00e0 un service \u00e0 son acceptation du d\u00e9p\u00f4t de traceurs sur son terminal.<\/p>\n<p>La CNIL ne consid\u00e8re pas cette pratique comme \u00e9tant ill\u00e9gale en soi, contrairement \u00e0 certains de ses homologues europ\u00e9ens.<\/p>\n<p>Elle souligne n\u00e9anmoins que le consentement doit \u00eatre libre et que les alternatives propos\u00e9es \u00e0 l\u2019utilisateur doivent \u00eatre pr\u00e9sent\u00e9es de mani\u00e8re \u00e9quilibr\u00e9e, sans l\u2019inciter \u00e0 recourir \u00e0 une option plut\u00f4t qu\u2019\u00e0 une autre (par exemple, en rendant un choix plus complexe que l\u2019autre).<\/p>\n<p>Il faut \u00e9galement que le consentement soit \u00e9clair\u00e9, c\u2019est-\u00e0-dire que les personnes aient une compr\u00e9hension compl\u00e8te et claire des cons\u00e9quences de leurs choix.<\/p>\n<p>Ces d\u00e9cisions de la CNIL sont aussi l\u2019aboutissement de plaintes d\u00e9pos\u00e9es par l\u2019ONG noyb il y a plus de deux ans aupr\u00e8s de nombreuses autorit\u00e9s de protection des donn\u00e9es (APD) en Europe, concernant principalement le ph\u00e9nom\u00e8ne des cookie walls ou pay or okay (payer ou accepter) et la question de la transparence de la collecte de donn\u00e9es.<\/p>\n<p>Ainsi mi-ao\u00fbt, la Cour administrative f\u00e9d\u00e9rale autrichienne a suivi l&rsquo;avis de l\u2019APD autrichienne et estim\u00e9 que l\u2019existence de plusieurs finalit\u00e9s au d\u00e9p\u00f4t de cookies n\u00e9cessite un consentement distinct.<\/p>\n<p>Selon la cour, le regroupement de diff\u00e9rentes finalit\u00e9s de traitement porterait atteinte \u00e0 la libert\u00e9 de d\u00e9cision et rendrait le consentement invalide.<\/p>\n<p>\u00ab Cette granularit\u00e9 est \u00e9troitement li\u00e9e \u00e0 l&rsquo;exigence selon laquelle le consentement doit \u00eatre donn\u00e9 pour une finalit\u00e9 sp\u00e9cifique \u00bb, indique l&rsquo;expos\u00e9 des motifs du jugement.<\/p>\n<p>Ces derniers d\u00e9veloppements confirment la position des autorit\u00e9s de contr\u00f4le selon laquelle le cadre l\u00e9gal, et en particulier la directive ePrivacy, s\u2019applique strictement au consentement, en particulier pour les cookies non essentiels.<\/p>\n<p>Les autorit\u00e9s ne tol\u00e8rent plus les consentements \u201cpar d\u00e9faut\u201d ni les interfaces d\u2019information floues.<\/p>\n<h4><strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;<\/strong><\/h4>\n<h4><img decoding=\"async\" src=\"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/05\/france_1778073011246.jpg\" alt=\"\" width=\"140\" height=\"94\"><\/h4>\n<p>Auditionn\u00e9 par le S\u00e9nat cet \u00e9t\u00e9, <strong>Anton Carniaux, directeur des affaires publiques et juridiques de Microsoft France, a admis qu\u2019il ne pouvait \u00ab garantir \u00bb que les donn\u00e9es des Fran\u00e7ais h\u00e9berg\u00e9es en Europe ne seraient jamais transmises au gouvernement am\u00e9ricain<\/strong> en vertu du Cloud Act, m\u00eame si \u00ab cela ne s\u2019est jamais produit \u00bb.<\/p>\n<p>Le gouvernement danois a annonc\u00e9, dans ce contexte de d\u00e9pendance aux g\u00e9ants am\u00e9ricains, le lancement officiel d&rsquo;une initiative visant \u00e0 \u00e9valuer l&rsquo;int\u00e9gration de solutions open-source au sein de ses services publics.<\/p>\n<p>Le 9 septembre, la DGE et la DGCCRF ont publi\u00e9 le projet de d\u00e9signation des autorit\u00e9s nationales en charge de la mise en \u0153uvre du r\u00e8glement europ\u00e9en sur l&rsquo;IA.<\/p>\n<p>Le document comprend un sch\u00e9ma indiquant les \u2013 nombreuses &#8211; autorit\u00e9s comp\u00e9tentes en fonction des articles du r\u00e8glement concern\u00e9s et des finalit\u00e9s des traitements par IA.<\/p>\n<p>On peut d\u00e9sormais, gr\u00e2ce au travail du chef adjoint de la mission juridique de la DINUM, consulter la cartographie des contr\u00f4les de la CNIL par ann\u00e9e et secteur d\u2019activit\u00e9.<\/p>\n<p>La cartographie se concentre sur ces contr\u00f4les et ne reprend pas toutes les actions de la CNIL telles que sensibilisation sur le terrain, mises en demeure, sanctions, etc.<\/p>\n<p>Elle est constitu\u00e9e sur la base des donn\u00e9es que la CNIL diffuse sur data.gouv.<\/p>\n<h4>&nbsp;<\/h4>\n<h4><img decoding=\"async\" src=\"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/05\/Europe_1778073054614.jpg\" alt=\"\" width=\"140\" height=\"93\"><\/h4>\n<h4><strong>Euroopa institutsioonid ja organid <\/strong><\/h4>\n<p>L\u2019actualit\u00e9 europ\u00e9enne est dense en cette p\u00e9riode de rentr\u00e9e, en raison de l\u2019activit\u00e9 des institutions et en particulier de la Cour de justice de l\u2019Union europ\u00e9enne (CJUE).<\/p>\n<p>La proposition de r\u00e8glement relative au contr\u00f4le des communications (\u00ab Chat control \u00bb), visant \u00e0 pr\u00e9venir et combattre les abus sexuels commis sur des enfants, est \u00e0 nouveau \u00e0 l&rsquo;ordre du jour du Conseil europ\u00e9en du 12 septembre 2025 sous pr\u00e9sidence danoise.<\/p>\n<p>La proposition r\u00e9vis\u00e9e pr\u00e9voit la possibilit\u00e9 de scanner les communications sur le terminal de l\u2019utilisateur avant leur envoi et constitue aux yeux de nombreux scientifiques et de la soci\u00e9t\u00e9 civile un recul par rapport au texte de la pr\u00e9sidence polonaise.<\/p>\n<p>Une nouvelle lettre ouverte (la quatri\u00e8me sur ce sujet) sign\u00e9e par plus de 600 scientifiques de 34 pays a ainsi \u00e9t\u00e9 publi\u00e9e le 8 septembre.<\/p>\n<p>Elle insiste sur l\u2019inefficacit\u00e9 et les risques que fait courir cette proposition en mati\u00e8re de chiffrement et mentionne les alternatives possibles.<\/p>\n<p>Le 4 septembre, la Commission europ\u00e9enne a lanc\u00e9 le processus visant \u00e0 adopter une d\u00e9cision d&rsquo;ad\u00e9quation en mati\u00e8re de protection des donn\u00e9es avec le Br\u00e9sil.<\/p>\n<p>Une fois adopt\u00e9e, cette d\u00e9cision sera la premi\u00e8re d\u00e9cision d&rsquo;ad\u00e9quation pour l&rsquo;Am\u00e9rique latine depuis celles concernant l&rsquo;Argentine le 3 juin 2003 et l&rsquo;Uruguay le 21 ao\u00fbt 2012.<\/p>\n<p>Les autorit\u00e9s br\u00e9siliennes ont \u00e9galement engag\u00e9 un processus visant \u00e0 adopter une d\u00e9cision \u00e9quivalente afin de permettre la libre circulation des donn\u00e9es br\u00e9siliennes vers l&rsquo;UE.<\/p>\n<p>Les prochaines \u00e9tapes consisteront \u00e0 soumettre pour avis le projet de d\u00e9cision au Comit\u00e9 europ\u00e9en de la protection des donn\u00e9es (EDPB) et au Conseil des ministres repr\u00e9sentant les \u00c9tats membres de l&rsquo;UE.<\/p>\n<p>Le Parlement europ\u00e9en examinera \u00e9galement le projet.<\/p>\n<p>Le 5 septembre, <strong>la Commission europ\u00e9enne a annonc\u00e9 infliger une amende de 2,95 milliards d&rsquo;euros \u00e0 Google<\/strong> pour avoir enfreint les r\u00e8gles antitrust de l&rsquo;UE en faussant la concurrence dans le secteur des technologies publicitaires (\u00ab adtech \u00bb).<\/p>\n<p>Google aurait favoris\u00e9 ses propres services de technologie publicitaire en ligne au d\u00e9triment des fournisseurs concurrents de services de technologie publicitaire, des annonceurs et des \u00e9diteurs en ligne.<\/p>\n<p>La Commission a ordonn\u00e9 \u00e0 Google de mettre fin \u00e0 ces pratiques d&rsquo;auto-pr\u00e9f\u00e9rence et de mettre en \u0153uvre des mesures visant \u00e0 \u00e9liminer les conflits d&rsquo;int\u00e9r\u00eats inh\u00e9rents \u00e0 sa cha\u00eene d&rsquo;approvisionnement adtech.<\/p>\n<p>Google dispose d\u00e9sormais de 60 jours pour informer la Commission de la mani\u00e8re dont elle entend s&rsquo;y prendre.<\/p>\n<p>Cette sanction a suscit\u00e9 une r\u00e9action imm\u00e9diate des Etats-Unis, Donald Trump ayant indiqu\u00e9 son intention de prendre des mesures de r\u00e9torsion \u00e0 l\u2019\u00e9gard de l\u2019UE.<\/p>\n<p>Le 3 septembre, dans sa d\u00e9cision T-553\/23 | Latombe v Commission, le <strong>Tribunal de l&rsquo;Union europ\u00e9enne a rejet\u00e9 l\u2019action du d\u00e9put\u00e9 Philippe Latombe visant \u00e0 annuler la troisi\u00e8me version de l&rsquo;accord sur le transfert de donn\u00e9es entre l&rsquo;UE et les \u00c9tats-Unis,<\/strong> le Data Protection Framework (DPF), estimant que les \u00c9tats-Unis \u00ab garantissaient un niveau ad\u00e9quat de protection des donn\u00e9es \u00e0 caract\u00e8re personnel \u00bb.<\/p>\n<p>M.soulignait notamment que l\u2019organe de recours am\u00e9ricain, la \u00ab Data Protection Review Court \u00bb (DPRC) n&rsquo;est pas impartial et d\u00e9pend du pouvoir ex\u00e9cutif.<\/p>\n<p>Il pointait en outre la pratique des services de renseignement consistant \u00e0 collecter en masse des donn\u00e9es \u00e0 caract\u00e8re personnel transitant depuis l&rsquo;Union europ\u00e9enne, sans l&rsquo;autorisation pr\u00e9alable d&rsquo;un juge ou d&rsquo;une autorit\u00e9 administrative ind\u00e9pendante, et donc sans encadrement suffisamment clair et pr\u00e9cis.<\/p>\n<p>Le Tribunal rejette le recours en annulation.<\/p>\n<p>Il souligne que le fonctionnement de la DPRC est soumis \u00e0 une s\u00e9rie de garanties, que la Commission europ\u00e9enne contr\u00f4le l\u2019application du DPF, et juge suffisant que les activit\u00e9s de renseignement men\u00e9es par les agences am\u00e9ricaines soient soumises \u00e0 un contr\u00f4le judiciaire a posteriori par la DPRC.<\/p>\n<p>La d\u00e9cision du Tribunal de l\u2019UE peut faire l\u2019objet d\u2019un recours devant la CJUE, et le d\u00e9put\u00e9 Philippe Latombe a d\u00e9j\u00e0 exprim\u00e9 son intention d\u2019intenter un tel recours.<\/p>\n<p>La CJUE a retoqu\u00e9 le 4 septembre dans un arr\u00eat important (affaire C-413\/23 P | CEPD\/CRU) une d\u00e9cision du tribunal de l\u2019UE relative \u00e0 la notion de donn\u00e9e \u00e0 caract\u00e8re personnel.<\/p>\n<p>Elle se prononce sur le recours du Contr\u00f4leur europ\u00e9en de la protection des donn\u00e9es (EDPS) concernant l\u2019arr\u00eat du tribunal de l\u2019UE qui annulait sa d\u00e9cision de 2020.<\/p>\n<p>Dans cette d\u00e9cision, l\u2019EDPS avait conclu que le Conseil europ\u00e9en de r\u00e9solution unique (CRU) avait enfreint le RGPD des institutions europ\u00e9ennes en communiquant \u00e0 un cabinet comptable les commentaires de cr\u00e9anciers et d\u2019actionnaires sur la proc\u00e9dure de faillite d&rsquo;une banque espagnole.<\/p>\n<p><strong>La CJUE estime que les opinions personnelles des individus constituent des informations \u00e0 caract\u00e8re personnel et que le Tribunal aurait d\u00fb les consid\u00e9rer comme telles. <\/strong><\/p>\n<p>Elle estime \u00e9galement que le risque de r\u00e9identification li\u00e9 au traitement et au transfert de donn\u00e9es \u00e0 caract\u00e8re personnel doit \u00eatre \u00e9valu\u00e9 au cas par cas au moment de la collecte, et que le Tribunal a commis une erreur en annulant la d\u00e9cision initiale du CEPD, en partie parce qu&rsquo;il n&rsquo;avait pas d\u00e9termin\u00e9 si le contenu des commentaires pseudonymis\u00e9s contenait effectivement des informations \u00e0 caract\u00e8re personnel.<\/p>\n<p>La CJUE s&rsquo;est toutefois rang\u00e9e du c\u00f4t\u00e9 du CRU sur la question de savoir dans quelles conditions les donn\u00e9es pseudonymis\u00e9es peuvent \u00e9galement \u00eatre des donn\u00e9es \u00e0 caract\u00e8re personnel, en \u00e9crivant dans sa d\u00e9cision que <strong>\u00ab les donn\u00e9es pseudonymis\u00e9es ne doivent pas \u00eatre consid\u00e9r\u00e9es comme constituant, dans tous les cas et pour chaque personne, des donn\u00e9es \u00e0 caract\u00e8re personnel aux fins de l&rsquo;application (du RGPD)<\/strong> dans la mesure o\u00f9 la pseudonymisation peut, selon les circonstances de l&rsquo;esp\u00e8ce, emp\u00eacher effectivement des personnes autres que le responsable du traitement d&rsquo;identifier la personne concern\u00e9e de telle sorte que, pour elles, la personne concern\u00e9e n&rsquo;est pas ou n&rsquo;est plus identifiable \u00bb.<\/p>\n<p>Dans un autre arr\u00eat \u00e9galement dat\u00e9 du 4 septembre (arr\u00eat C 655\/23, IP contre Quirin Privatbank AG), la Cour s\u2019est prononc\u00e9e sur l\u2019existence d\u2019un droit d\u2019injonction pr\u00e9ventive d\u2019abstention \u00e0 l\u2019encontre du responsable du traitement, et sur l\u2019\u00e9tendue du dommage moral.<\/p>\n<p>La Cour consid\u00e8re que le RGPD n\u2019offre pas de recours judiciaire pr\u00e9ventif contre les traitements illicites futurs, mais que les \u00c9tats membres peuvent le pr\u00e9voir.<\/p>\n<p>Elle a \u00e9galement pr\u00e9cis\u00e9 que des sentiments tels que l\u2019humiliation ou l\u2019inqui\u00e9tude peuvent suffire \u00e0 \u00e9tablir un dommage moral, \u00e0 condition d\u2019en apporter la preuve.<\/p>\n<p>Elle ajoute que la gravit\u00e9 de la faute du responsable de traitement ou l\u2019obtention d\u2019une injonction ne doivent pas influencer le montant de l\u2019indemnisation, qui reste exclusivement compensatoire.<\/p>\n<h4>&nbsp;<\/h4>\n<h4><strong>Uudised Euroopa Liidu liikmesriikidest. <\/strong><\/h4>\n<p>En Allemagne, la Cour f\u00e9d\u00e9rale du travail a estim\u00e9 qu&rsquo;un employeur avait trait\u00e9 ill\u00e9galement les donn\u00e9es relatives \u00e0 la sant\u00e9 d&rsquo;un employ\u00e9 en le faisant surveiller afin de v\u00e9rifier s&rsquo;il simulait son incapacit\u00e9 \u00e0 travailler.<\/p>\n<p>Elle a \u00e9galement accord\u00e9 \u00e0 l&#8217;employ\u00e9 1500 \u20ac de dommages-int\u00e9r\u00eats immat\u00e9riels.<\/p>\n<p>L\u2019APD belge a r\u00e9primand\u00e9 un homme politique qui avait collect\u00e9 l&rsquo;adresse \u00e9lectronique d&rsquo;une personne \u00e0 partir d&rsquo;une source publique et lui avait envoy\u00e9 des messages \u00e0 caract\u00e8re politique, en violation des principes de lic\u00e9it\u00e9, de limitation des finalit\u00e9s et de transparence du RGPD.<\/p>\n<p>En Espagne, Loro Parque, une soci\u00e9t\u00e9 gestionnaire d&rsquo;un zoo et d&rsquo;un parc aquatique, a \u00e9t\u00e9 condamn\u00e9e par l\u2019APD \u00e0 une amende de 250 000 \u20ac pour avoir collect\u00e9 des empreintes digitales sans information pr\u00e9alable ni consentement : les personnes concern\u00e9es \u00e9taient tenues de fournir leurs empreintes digitales si elles disposaient de billets promotionnels leur donnant acc\u00e8s aux deux parcs avec un seul billet.<\/p>\n<p>En outre, l\u2019APD a inflig\u00e9 une amende de 500 000 euros \u00e0 la Chambre de commerce espagnole pour avoir transf\u00e9r\u00e9 les num\u00e9ros d&rsquo;identification fiscale de travailleurs ind\u00e9pendants \u00e0 des entreprises priv\u00e9es sans base l\u00e9gale.<\/p>\n<p>En Italie, l\u2019APD a inflig\u00e9 une amende de 50 000 \u20ac \u00e0 une entreprise automobile.<\/p>\n<p>Cette derni\u00e8re avait organis\u00e9 des entretiens de \u00ab retour au travail \u00bb avec ses employ\u00e9s apr\u00e8s leur absence, donnant lieu \u00e0 une collecte excessive de donn\u00e9es, incluant des donn\u00e9es sensibles.<\/p>\n<p>L\u2019APD pointe \u00e9galement une violation des principes de transparence et de validit\u00e9 du consentement des employ\u00e9s.<\/p>\n<p>L\u2019APD lithuanienne a impos\u00e9 \u00e0 la soci\u00e9t\u00e9 Vinted d\u2019arr\u00eater de collecter les num\u00e9ros de t\u00e9l\u00e9phone de ses clients \u00e0 des fins de v\u00e9rification de leur compte.<\/p>\n<p>Elle a d\u2019abord consid\u00e9r\u00e9 que les raisons invoqu\u00e9es par Vinted, \u00e0 savoir la v\u00e9rification des comptes des utilisateurs et la garantie de la s\u00e9curit\u00e9 de la plateforme, ne constituaient pas un aspect essentiel du contrat entre le responsable du traitement et la personne concern\u00e9e.<\/p>\n<p>Elle a \u00e9galement not\u00e9 que les conditions d&rsquo;utilisation mentionnaient d\u2019autres moyens possibles de v\u00e9rifier l&rsquo;identit\u00e9 d&rsquo;un utilisateur, et que le traitement des donn\u00e9es \u00e0 caract\u00e8re personnel ne r\u00e9pondait donc pas au crit\u00e8re de n\u00e9cessit\u00e9 pr\u00e9vu \u00e0 l&rsquo;article 6(1)(b) du RGPD.<\/p>\n<p>La Cour administrative supr\u00eame des Pays-Bas a estim\u00e9 qu&rsquo;un \u00e9tablissement de soins de sant\u00e9 mentale n&rsquo;\u00e9tait pas tenu de se conformer \u00e0 une demande d&rsquo;effacement de donn\u00e9es.<\/p>\n<p>La conservation des donn\u00e9es \u00e9tait n\u00e9cessaire dans le cadre du contrat de traitement m\u00e9dical et pour la gestion des services de l&rsquo;\u00e9tablissement.<\/p>\n<p><strong>En Pologne, la banque ING Bank \u015al\u0105ski s&rsquo;est vu infliger une amende de 4 300 000 \u20ac pour avoir scann\u00e9 des documents d&rsquo;identit\u00e9 sans motif l\u00e9gitime ni \u00e9valuation des risques<\/strong>.<\/p>\n<p>L\u2019APD a constat\u00e9 que la banque avait trait\u00e9 des donn\u00e9es sensibles, notamment des num\u00e9ros PESEL et des d\u00e9tails de documents, sans que cela soit n\u00e9cessaire, enfreignant ainsi l&rsquo;approche fond\u00e9e sur les risques requise par la r\u00e9glementation en mati\u00e8re de lutte contre le blanchiment d&rsquo;argent.<\/p>\n<h4><strong>&nbsp;<\/strong><\/h4>\n<h4><strong><img decoding=\"async\" src=\"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/05\/INTERNATIO_1778073279221.jpg\" alt=\"\" width=\"150\" height=\"85\"><\/strong><\/h4>\n<p><strong>La Chine renforce ses r\u00e8gles autour des transferts de donn\u00e9es \u00e0 l\u2019\u00e9tranger. <\/strong><\/p>\n<p>La succursale de Dior \u00e0 Shanghai est accus\u00e9e par les autorit\u00e9s de s\u00e9curit\u00e9 publique chinoises d\u2019avoir transf\u00e9r\u00e9 ill\u00e9galement des donn\u00e9es de clients vers le si\u00e8ge en France, sans respecter les r\u00e8gles d\u2019\u00e9valuation de s\u00e9curit\u00e9 obligatoires, de notification des utilisateurs et de chiffrement.<\/p>\n<p>La succursale a fait l\u2019objet d\u2019une sanction administrative.<\/p>\n<p><strong>Aux Etats-Unis, 44 procureurs g\u00e9n\u00e9raux ont envoy\u00e9 une lettre \u00e0 13 entreprises d&rsquo;IA, dont OpenAI, CharacterAI, Replika et Meta, leur indiquant qu&rsquo;elles seraient tenues responsables si elles causaient du tort \u00e0 des enfants.<\/strong><\/p>\n<p>La lettre met en avant des r\u00e9v\u00e9lations r\u00e9centes concernant les directives techniques de Meta pour Meta AI et les chatbots de Facebook, WhatsApp et Instagram.<\/p>\n<p>Ce document, approuv\u00e9 par les \u00e9quipes juridiques, politiques et techniques de l&rsquo;entreprise, autorisait les chatbots \u00e0 inviter les enfants \u00e0 avoir des \u00e9changes romantiques ou s\u00e9ducteurs avec le chatbot, incluant des commentaires sur l&rsquo;apparence des enfants ainsi que des sc\u00e9narios de jeux de r\u00f4le.<\/p>\n<p>Le blog \u00ab Tech Community \u00bb de Microsoft a annonc\u00e9 fin ao\u00fbt que la derni\u00e8re mise \u00e0 jour de MS Word pour Windows sauvegarde automatiquement et par d\u00e9faut les fichiers Word des utilisateurs sur son cloud (OneDrive).<\/p>\n<p>Cette mise \u00e0 jour est pr\u00e9sent\u00e9e par Microsoft comme une am\u00e9lioration en mati\u00e8re de s\u00e9curit\u00e9, d\u2019acc\u00e8s, de travail en \u00e9quipe et d\u2019utilisation de l\u2019IA.<\/p>\n<p>S\u2019il est possible de modifier ces param\u00e8tres dans les pr\u00e9f\u00e9rences de Word, le chargement par d\u00e9faut des documents sur un cloud am\u00e9ricain pose des questions en lien avec le RGPD, concernant la confidentialit\u00e9 des donn\u00e9es et la question de l\u2019accessibilit\u00e9 de ces donn\u00e9es par les autorit\u00e9s publiques des Etats-Unis.<\/p>\n<p><strong>Les lunettes intelligentes \u00ab Halo \u00bb suscitent l\u2019inqui\u00e9tude aupr\u00e8s des experts en IA.<\/strong><\/p>\n<p>L. Jarosvsky rapporte que ces nouvelles lunettes sont toujours activ\u00e9es, enregistrent tout et ne disposent d&rsquo;aucun indicateur pour avertir les personnes qu&rsquo;elles sont enregistr\u00e9es.<\/p>\n<p>Dans une interview accord\u00e9e \u00e0 TechCrunch, les fondateurs de Halo auraient d\u00e9clin\u00e9 leur responsabilit\u00e9 en indiquant que dans les \u00c9tats am\u00e9ricains o\u00f9 il est ill\u00e9gal d&rsquo;enregistrer secr\u00e8tement des conversations sans le consentement de l&rsquo;autre personne, il appartient \u00e0 l&rsquo;utilisateur d&rsquo;obtenir ce consentement avant d&rsquo;utiliser les lunettes.<\/p>","protected":false},"excerpt":{"rendered":"<p>Veille Juridique n\u00b086 \u2013 ao\u00fbt 2025.&nbsp; &nbsp; Cookies et ciblage des internautes : \u00e9tat des lieux. La CNIL a inflig\u00e9 le 1er septembre une amende de 325 millions d&rsquo;euros \u00e0 la soci\u00e9t\u00e9 Google et de 150 millions d&rsquo;euros \u00e0 la filiale irlandaise du groupe Shein, deux montants qui vont sensiblement rehausser la moyenne des sanctions [&hellip;]<\/p>","protected":false},"author":1,"featured_media":14105,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[35],"tags":[],"class_list":["post-14109","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veille-juridique"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cookies et ciblage des internautes : \u00e9tat des lieux - Viqtor<\/title>\n<meta name=\"description\" content=\"Cookies et ciblage des internautes : \u00e9tat des lieux - Viqtor\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/viqtor.eu\/et\/cookies-et-ciblage-des-internautes-etat-des-lieux\/\" \/>\n<meta property=\"og:locale\" content=\"et_EE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cookies et ciblage des internautes : \u00e9tat des lieux - Viqtor\" \/>\n<meta property=\"og:description\" content=\"Cookies et ciblage des internautes : \u00e9tat des lieux - Viqtor\" \/>\n<meta property=\"og:url\" content=\"https:\/\/viqtor.eu\/et\/cookies-et-ciblage-des-internautes-etat-des-lieux\/\" \/>\n<meta property=\"og:site_name\" content=\"Viqtor\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T07:42:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/04\/widget-viqtor.png\" \/>\n<meta name=\"author\" content=\"Bruno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bruno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutit\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/viqtor.eu\/cookies-et-ciblage-des-internautes-etat-des-lieux\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/viqtor.eu\/cookies-et-ciblage-des-internautes-etat-des-lieux\/\"},\"author\":{\"name\":\"Bruno\",\"@id\":\"https:\/\/viqtor.eu\/#\/schema\/person\/3dbd9cc82a28f6cf1695c92eda0099ad\"},\"headline\":\"Cookies et ciblage des internautes : \u00e9tat des lieux\",\"datePublished\":\"2026-05-13T07:42:25+00:00\",\"dateModified\":\"2026-05-13T07:42:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/viqtor.eu\/cookies-et-ciblage-des-internautes-etat-des-lieux\/\"},\"wordCount\":3157,\"publisher\":{\"@id\":\"https:\/\/viqtor.eu\/#organization\"},\"image\":{\"@id\":\"https:\/\/viqtor.eu\/cookies-et-ciblage-des-internautes-etat-des-lieux\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/05\/04c1104f-9359-4b3d-bb87-4e52c82a601a_1778073576555.jpg\",\"articleSection\":[\"Veille juridique\"],\"inLanguage\":\"et\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/viqtor.eu\/cookies-et-ciblage-des-internautes-etat-des-lieux\/\",\"url\":\"https:\/\/viqtor.eu\/cookies-et-ciblage-des-internautes-etat-des-lieux\/\",\"name\":\"Cookies et ciblage des internautes : \u00e9tat des lieux - Viqtor\",\"isPartOf\":{\"@id\":\"https:\/\/viqtor.eu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/viqtor.eu\/cookies-et-ciblage-des-internautes-etat-des-lieux\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/viqtor.eu\/cookies-et-ciblage-des-internautes-etat-des-lieux\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/05\/04c1104f-9359-4b3d-bb87-4e52c82a601a_1778073576555.jpg\",\"datePublished\":\"2026-05-13T07:42:25+00:00\",\"dateModified\":\"2026-05-13T07:42:25+00:00\",\"description\":\"Cookies et ciblage des internautes : \u00e9tat des lieux - Viqtor\",\"breadcrumb\":{\"@id\":\"https:\/\/viqtor.eu\/cookies-et-ciblage-des-internautes-etat-des-lieux\/#breadcrumb\"},\"inLanguage\":\"et\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/viqtor.eu\/cookies-et-ciblage-des-internautes-etat-des-lieux\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"et\",\"@id\":\"https:\/\/viqtor.eu\/cookies-et-ciblage-des-internautes-etat-des-lieux\/#primaryimage\",\"url\":\"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/05\/04c1104f-9359-4b3d-bb87-4e52c82a601a_1778073576555.jpg\",\"contentUrl\":\"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/05\/04c1104f-9359-4b3d-bb87-4e52c82a601a_1778073576555.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/viqtor.eu\/cookies-et-ciblage-des-internautes-etat-des-lieux\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/viqtor.eu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cookies et ciblage des internautes : \u00e9tat des lieux\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/viqtor.eu\/#website\",\"url\":\"https:\/\/viqtor.eu\/\",\"name\":\"Viqtor\",\"description\":\"Faites du RGPD une opportunit\u00e9 pour votre entreprise.\",\"publisher\":{\"@id\":\"https:\/\/viqtor.eu\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/viqtor.eu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"et\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/viqtor.eu\/#organization\",\"name\":\"viqtor.eu\",\"url\":\"https:\/\/viqtor.eu\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"et\",\"@id\":\"https:\/\/viqtor.eu\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/viqtor.eu\/wp-content\/uploads\/2023\/06\/favicon-noir.svg\",\"contentUrl\":\"https:\/\/viqtor.eu\/wp-content\/uploads\/2023\/06\/favicon-noir.svg\",\"width\":108,\"height\":86,\"caption\":\"viqtor.eu\"},\"image\":{\"@id\":\"https:\/\/viqtor.eu\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/viqtor.eu\/#\/schema\/person\/3dbd9cc82a28f6cf1695c92eda0099ad\",\"name\":\"Bruno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"et\",\"@id\":\"https:\/\/viqtor.eu\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e5a596f9489de15bfe046e97fb771f63589b601ca7e81ccc2bb9a23582f441a3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e5a596f9489de15bfe046e97fb771f63589b601ca7e81ccc2bb9a23582f441a3?s=96&d=mm&r=g\",\"caption\":\"Bruno\"},\"sameAs\":[\"https:\/\/exciting-panini.13-37-234-21.plesk.page\"],\"url\":\"https:\/\/viqtor.eu\/et\/author\/mouad_zxum2ebi\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cookies et ciblage des internautes : \u00e9tat des lieux - Viqtor","description":"Cookies et ciblage des internautes : \u00e9tat des lieux - Viqtor","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/viqtor.eu\/et\/cookies-et-ciblage-des-internautes-etat-des-lieux\/","og_locale":"et_EE","og_type":"article","og_title":"Cookies et ciblage des internautes : \u00e9tat des lieux - Viqtor","og_description":"Cookies et ciblage des internautes : \u00e9tat des lieux - Viqtor","og_url":"https:\/\/viqtor.eu\/et\/cookies-et-ciblage-des-internautes-etat-des-lieux\/","og_site_name":"Viqtor","article_published_time":"2026-05-13T07:42:25+00:00","og_image":[{"url":"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/04\/widget-viqtor.png"}],"author":"Bruno","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bruno","Est. reading time":"15 minutit"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/viqtor.eu\/cookies-et-ciblage-des-internautes-etat-des-lieux\/#article","isPartOf":{"@id":"https:\/\/viqtor.eu\/cookies-et-ciblage-des-internautes-etat-des-lieux\/"},"author":{"name":"Bruno","@id":"https:\/\/viqtor.eu\/#\/schema\/person\/3dbd9cc82a28f6cf1695c92eda0099ad"},"headline":"Cookies et ciblage des internautes : \u00e9tat des lieux","datePublished":"2026-05-13T07:42:25+00:00","dateModified":"2026-05-13T07:42:25+00:00","mainEntityOfPage":{"@id":"https:\/\/viqtor.eu\/cookies-et-ciblage-des-internautes-etat-des-lieux\/"},"wordCount":3157,"publisher":{"@id":"https:\/\/viqtor.eu\/#organization"},"image":{"@id":"https:\/\/viqtor.eu\/cookies-et-ciblage-des-internautes-etat-des-lieux\/#primaryimage"},"thumbnailUrl":"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/05\/04c1104f-9359-4b3d-bb87-4e52c82a601a_1778073576555.jpg","articleSection":["Veille juridique"],"inLanguage":"et"},{"@type":"WebPage","@id":"https:\/\/viqtor.eu\/cookies-et-ciblage-des-internautes-etat-des-lieux\/","url":"https:\/\/viqtor.eu\/cookies-et-ciblage-des-internautes-etat-des-lieux\/","name":"Cookies et ciblage des internautes : \u00e9tat des lieux - Viqtor","isPartOf":{"@id":"https:\/\/viqtor.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/viqtor.eu\/cookies-et-ciblage-des-internautes-etat-des-lieux\/#primaryimage"},"image":{"@id":"https:\/\/viqtor.eu\/cookies-et-ciblage-des-internautes-etat-des-lieux\/#primaryimage"},"thumbnailUrl":"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/05\/04c1104f-9359-4b3d-bb87-4e52c82a601a_1778073576555.jpg","datePublished":"2026-05-13T07:42:25+00:00","dateModified":"2026-05-13T07:42:25+00:00","description":"Cookies et ciblage des internautes : \u00e9tat des lieux - Viqtor","breadcrumb":{"@id":"https:\/\/viqtor.eu\/cookies-et-ciblage-des-internautes-etat-des-lieux\/#breadcrumb"},"inLanguage":"et","potentialAction":[{"@type":"ReadAction","target":["https:\/\/viqtor.eu\/cookies-et-ciblage-des-internautes-etat-des-lieux\/"]}]},{"@type":"ImageObject","inLanguage":"et","@id":"https:\/\/viqtor.eu\/cookies-et-ciblage-des-internautes-etat-des-lieux\/#primaryimage","url":"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/05\/04c1104f-9359-4b3d-bb87-4e52c82a601a_1778073576555.jpg","contentUrl":"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/05\/04c1104f-9359-4b3d-bb87-4e52c82a601a_1778073576555.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/viqtor.eu\/cookies-et-ciblage-des-internautes-etat-des-lieux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/viqtor.eu\/"},{"@type":"ListItem","position":2,"name":"Cookies et ciblage des internautes : \u00e9tat des lieux"}]},{"@type":"WebSite","@id":"https:\/\/viqtor.eu\/#website","url":"https:\/\/viqtor.eu\/","name":"Viqtor","description":"Faites du RGPD une opportunit\u00e9 pour votre entreprise.","publisher":{"@id":"https:\/\/viqtor.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/viqtor.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"et"},{"@type":"Organization","@id":"https:\/\/viqtor.eu\/#organization","name":"viqtor.eu","url":"https:\/\/viqtor.eu\/","logo":{"@type":"ImageObject","inLanguage":"et","@id":"https:\/\/viqtor.eu\/#\/schema\/logo\/image\/","url":"https:\/\/viqtor.eu\/wp-content\/uploads\/2023\/06\/favicon-noir.svg","contentUrl":"https:\/\/viqtor.eu\/wp-content\/uploads\/2023\/06\/favicon-noir.svg","width":108,"height":86,"caption":"viqtor.eu"},"image":{"@id":"https:\/\/viqtor.eu\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/viqtor.eu\/#\/schema\/person\/3dbd9cc82a28f6cf1695c92eda0099ad","name":"Bruno","image":{"@type":"ImageObject","inLanguage":"et","@id":"https:\/\/viqtor.eu\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e5a596f9489de15bfe046e97fb771f63589b601ca7e81ccc2bb9a23582f441a3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e5a596f9489de15bfe046e97fb771f63589b601ca7e81ccc2bb9a23582f441a3?s=96&d=mm&r=g","caption":"Bruno"},"sameAs":["https:\/\/exciting-panini.13-37-234-21.plesk.page"],"url":"https:\/\/viqtor.eu\/et\/author\/mouad_zxum2ebi\/"}]}},"_links":{"self":[{"href":"https:\/\/viqtor.eu\/et\/wp-json\/wp\/v2\/posts\/14109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/viqtor.eu\/et\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/viqtor.eu\/et\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/viqtor.eu\/et\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/viqtor.eu\/et\/wp-json\/wp\/v2\/comments?post=14109"}],"version-history":[{"count":0,"href":"https:\/\/viqtor.eu\/et\/wp-json\/wp\/v2\/posts\/14109\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/viqtor.eu\/et\/wp-json\/wp\/v2\/media\/14105"}],"wp:attachment":[{"href":"https:\/\/viqtor.eu\/et\/wp-json\/wp\/v2\/media?parent=14109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/viqtor.eu\/et\/wp-json\/wp\/v2\/categories?post=14109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/viqtor.eu\/et\/wp-json\/wp\/v2\/tags?post=14109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}