{"id":14099,"date":"2026-05-13T07:40:05","date_gmt":"2026-05-13T07:40:05","guid":{"rendered":"https:\/\/viqtor.eu\/cinq-ans-apres-le-brexit-etat-des-lieux-au-royaume-uni\/"},"modified":"2026-05-13T07:40:05","modified_gmt":"2026-05-13T07:40:05","slug":"cinq-ans-apres-le-brexit-etat-des-lieux-au-royaume-uni","status":"publish","type":"post","link":"https:\/\/viqtor.eu\/el\/cinq-ans-apres-le-brexit-etat-des-lieux-au-royaume-uni\/","title":{"rendered":"\u03a0\u03ad\u03bd\u03c4\u03b5 \u03c7\u03c1\u03cc\u03bd\u03b9\u03b1 \u03bc\u03b5\u03c4\u03ac \u03c4\u03bf Brexit: \u03bc\u03b9\u03b1 \u03bc\u03b1\u03c4\u03b9\u03ac \u03c3\u03c4\u03b7\u03bd \u03ba\u03b1\u03c4\u03ac\u03c3\u03c4\u03b1\u03c3\u03b7 \u03c3\u03c4\u03bf \u0397\u03bd\u03c9\u03bc\u03ad\u03bd\u03bf \u0392\u03b1\u03c3\u03af\u03bb\u03b5\u03b9\u03bf"},"content":{"rendered":"<h4><strong>Veille Juridique n\u00b087 \u2013 septembre 2025.&nbsp; <\/strong><\/h4>\n<h4><strong>&nbsp;<\/strong><\/h4>\n<h4><strong><u>Cinq ans apr\u00e8s le Brexit : \u00e9tat des lieux au Royaume-Uni.<\/u><\/strong><\/h4>\n<p>Depuis la sortie du Royaume-Uni de l\u2019Union europ\u00e9enne, le droit britannique de la protection des donn\u00e9es s\u2019\u00e9loigne lentement mais s\u00fbrement du cadre r\u00e9glementaire europ\u00e9en.<\/p>\n<p>S\u2019il y a une tendance de part et d\u2019autre de la Manche \u00e0 opter pour une simplification des normes, le Royaume-Uni a un temps d\u2019avance sur l\u2019Union europ\u00e9enne.<\/p>\n<p>Apr\u00e8s le Brexit, le Data Protection Act de 2018 (DPA) a \u00e9t\u00e9 modifi\u00e9 pour rester compl\u00e9mentaire au \u00ab UK GDPR \u00bb, version britannique du RGPD entr\u00e9e en vigueur le 1er janvier 2021.<\/p>\n<p>Le Royaume-Uni a \u00e9galement adopt\u00e9 les Privacy and Electronic Communications Regulations (PECR), qui mettent en \u0153uvre la directive europ\u00e9enne ePrivacy.<\/p>\n<p>Le Data Use and Access Act (DUAA), adopt\u00e9 le 19 juin 2025, est une r\u00e9forme majeure du r\u00e9gime britannique des donn\u00e9es personnelles.<\/p>\n<p>Il modifie et compl\u00e8te \u00e0 la fois le UK GDPR, le DPA et les PECR, et repr\u00e9sente un tournant strat\u00e9gique par lequel le Royaume-Uni s\u2019\u00e9loigne d\u2019une vision centr\u00e9e sur les droits fondamentaux pour adopter une logique plus pragmatique et pro-innovation.<\/p>\n<p>Ses principaux objectifs sont de :<\/p>\n<ul style=\"list-style-type: square;\">\n<li>Proposer une base l\u00e9gale \u00e9largie \u00ab&nbsp;d\u2019int\u00e9r\u00eats l\u00e9gitimes reconnus&nbsp;\u00bb pour certains traitements dont l\u2019archivage dans l\u2019int\u00e9r\u00eat public, la s\u00e9curit\u00e9 publique ou la fiscalit\u00e9,<\/li>\n<li>Donner la possibilit\u00e9 aux entreprises de suspendre le d\u00e9lai de r\u00e9ponse aux demandes d\u2019acc\u00e8s,<\/li>\n<li>Simplifier les r\u00e8gles sur les cookies ;<\/li>\n<li>Faciliter les transferts internationaux de donn\u00e9es ;<\/li>\n<li>Encourager l\u2019innovation dans les services num\u00e9riques et l\u2019IA, en assouplissant le cadre des d\u00e9cisions automatis\u00e9es ;<\/li>\n<li>Imposer le \u00ab privacy by design \u00bb dans les services num\u00e9riques visant les enfants,<\/li>\n<li>Permettre la mise en place d\u2019une identit\u00e9 num\u00e9rique,<\/li>\n<li>Simplifier les r\u00e8gles concernant les services de police et le renseignement.<\/li>\n<\/ul>\n<p>Certains pointent n\u00e9anmoins les risques de ces r\u00e9formes, et en particulier la fragilisation des droits des individus.<\/p>\n<p>En mati\u00e8re de d\u00e9cisions automatis\u00e9es, ils rel\u00e8vent par exemple le fiasco des r\u00e9sultats d\u2019examens \u00ab A level \u00bb de 2020, o\u00f9 des notes non pertinentes avaient \u00e9t\u00e9 attribu\u00e9es par un algorithme, et les erreurs dans des outils de d\u00e9tection de fraude du Department for Work and Pensions (DWP) ayant entra\u00een\u00e9 de nombreux pr\u00e9judices pour les personnes concern\u00e9es.<\/p>\n<p>Le projet d\u2019identit\u00e9 num\u00e9rique, annonc\u00e9 d\u00e9but octobre par le gouvernement, a quant \u00e0 lui provoqu\u00e9 une lev\u00e9e de boucliers, avec la signature d\u2019une p\u00e9tition par des millions de citoyens britanniques demandant le retrait du projet.<\/p>\n<p>Depuis quelques ann\u00e9es le gouvernement britannique fait \u00e9galement pression pour mettre en place des m\u00e9canismes permettant l\u2019acc\u00e8s aux contenus chiffr\u00e9s des communications : la discussion publique se concentre sur des approches techniques controvers\u00e9es telles que le \u00ab client side scanning \u00bb (d\u00e9tection c\u00f4t\u00e9 client).<\/p>\n<p>Pr\u00e9cisons que l\u2019Union europ\u00e9enne discute actuellement d\u2019un sujet apparent\u00e9 : la proposition de r\u00e8glement CSAR visant \u00e0 pr\u00e9venir et combattre les abus sexuels commis sur des enfants est \u00e0 nouveau \u00e0 l&rsquo;ordre du jour du Conseil europ\u00e9en du 14 octobre.<\/p>\n<p>Cette proposition qui pr\u00e9voit la possibilit\u00e9 de scanner les communications sur le terminal de l\u2019utilisateur avant leur envoi constitue aux yeux de nombreux scientifiques et de la soci\u00e9t\u00e9 civile un projet \u00e0 la fois inefficace et particuli\u00e8rement dangereux pour les droits fondamentaux et le chiffrement lui-m\u00eame.<\/p>\n<p>L\u2019Union europ\u00e9enne tend \u00e9galement, aujourd\u2019hui, \u00e0 simplifier le cadre normatif concernant les donn\u00e9es via son \u00ab train de mesures omnibus sur le num\u00e9rique \u00bb.<\/p>\n<p>La Commission a lanc\u00e9 un appel \u00e0 contribution qui se termine le 14 octobre, portant sur les domaines de la l\u00e9gislation sur les donn\u00e9es, y compris les r\u00e8gles relatives aux cookies et autres technologies de suivi, le signalement des incidents de cybers\u00e9curit\u00e9 ainsi que certains aspects de la loi sur l&rsquo;intelligence artificielle.<\/p>\n<p>En ce qui concerne plus pr\u00e9cis\u00e9ment le RGPD, les sujets concern\u00e9s visent par exemple la limitation de l\u2019obligation de tenir un registre aux structures de plus de 500 salari\u00e9s, contre 250 actuellement. L\u2019Union europ\u00e9enne ne remet pas en question actuellement les principes essentiels du r\u00e8glement.<\/p>\n<p>De part et d\u2019autre de la Manche, les b\u00e9n\u00e9fices annonc\u00e9s en faveur de l\u2019industrie rel\u00e8vent de la r\u00e9duction des co\u00fbts de mise en conformit\u00e9.<\/p>\n<p>En revanche, les co\u00fbts de mise en \u0153uvre de la r\u00e9forme elle-m\u00eame, les co\u00fbts des erreurs ou des litiges, les co\u00fbts pour la confiance&nbsp;&nbsp; des consommateurs, sont moins bien connus. Cet argument a d\u2019ailleurs \u00e9t\u00e9 avanc\u00e9 lors du \u00ab dialogue de mise en \u0153uvre \u00bb organis\u00e9 par la Commission europ\u00e9enne mi-juillet. Le secteur priv\u00e9 a ainsi indiqu\u00e9 qu\u2019il avait \u00ab investi dans la conformit\u00e9 et qu&rsquo;une r\u00e9ouverture g\u00e9n\u00e9rale pourrait cr\u00e9er une incertitude, notamment dans le contexte des transferts internationaux de donn\u00e9es \u00bb.<\/p>\n<p>Aujourd\u2019hui, le rapport b\u00e9n\u00e9fices\/risques des r\u00e9formes britanniques et son impact sur les partenariats internationaux, et de fa\u00e7on plus d\u00e9cisive, sur le maintien de la d\u00e9cision d\u2019ad\u00e9quation du Royaume-Uni avec l\u2019UE, restent encore incertains.<\/p>\n<p>Le projet de d\u00e9cision d\u2019ad\u00e9quation de la Commission europ\u00e9enne est pourtant favorable \u00e0 une reconnaissance du niveau de protection du Royaume-Uni.<\/p>\n<p>Il doit toutefois \u00eatre soumis \u00e0 l\u2019avis du Comit\u00e9 europ\u00e9en de protection des donn\u00e9es et \u00eatre discut\u00e9 au Conseil.<\/p>\n<p>Souhaitons que la d\u00e9cision finale soit particuli\u00e8rement transparente quant aux crit\u00e8res pris en compte, compte tenu des modifications cons\u00e9quentes du droit britannique.<\/p>\n<p>Ceci appara\u00eet essentiel pour assurer \u00e0 l\u2019avenir une s\u00e9curit\u00e9 juridique suffisante aux entreprises europ\u00e9ennes comme \u00e0 celles \u00e9tablies hors UE.<\/p>\n<h4>&nbsp;<\/h4>\n<h4><strong><img decoding=\"async\" src=\"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/05\/france_1778076363047.jpg\" alt=\"\" width=\"140\" height=\"94\"> &nbsp; &nbsp; &nbsp;&nbsp;<\/strong><\/h4>\n<p>Le 18 septembre 2025, la CNIL a sanctionn\u00e9 la soci\u00e9t\u00e9 Samaritaine SAS d\u2019une amende de 100 000 euros pour avoir dissimul\u00e9 des cam\u00e9ras dans les r\u00e9serves du magasin du m\u00eame nom.<\/p>\n<p>Ces cam\u00e9ras prenaient l\u2019apparence de d\u00e9tecteurs de fum\u00e9es et permettaient d\u2019enregistrer le son.<\/p>\n<p>La CNIL a rappel\u00e9 qu\u2019un employeur peut installer des cam\u00e9ras dissimul\u00e9es dans des circonstances exceptionnelles et \u00e0 condition de m\u00e9nager un juste \u00e9quilibre entre l\u2019objectif poursuivi (la protection des biens et des personnes) et la protection de la vie priv\u00e9e des salari\u00e9s.<\/p>\n<p>Un tel dispositif pourrait par exemple \u00eatre autoris\u00e9 \u00e0 condition d\u2019\u00eatre temporaire et d\u00e9ploy\u00e9 apr\u00e8s analyse document\u00e9e de sa compatibilit\u00e9 avec le RGPD et au regard de circonstances exceptionnelles.<\/p>\n<p>Dans le cas pr\u00e9sent, la soci\u00e9t\u00e9 a bien rapport\u00e9 l\u2019existence de vols commis dans les r\u00e9serves et expliqu\u00e9 que le dispositif \u00e9tait temporaire, mais elle n\u2019a men\u00e9 aucune analyse pr\u00e9alable de conformit\u00e9 au RGPD, ni document\u00e9 le caract\u00e8re temporaire de l\u2019installation.<\/p>\n<p>La CNIL a \u00e9galement publi\u00e9 plusieurs contenus concernant la gestion des comptes inactifs pour les professionnels de l\u2019audiovisuel et des jeux vid\u00e9o, sur les dispositifs de vid\u00e9os dans les \u00e9tablissements scolaires ainsi que sur la g\u00e9olocalisation des enfants.<\/p>\n<p>L\u2019Assembl\u00e9e nationale a adopt\u00e9 le 9 septembre en commission sp\u00e9ciale le projet de loi R\u00e9silience sur la cybers\u00e9curit\u00e9.&nbsp;<\/p>\n<p>Philippe Latombe, pr\u00e9sident de la commission, a fait adopter un amendement visant \u00e0 sanctuariser le chiffrement de bout en bout dans l\u2019article 16 bis : \u00ab Il ne peut \u00eatre impos\u00e9 aux fournisseurs de services de chiffrement, y compris aux prestataires de services de confiance qualifi\u00e9s, l\u2019int\u00e9gration de dispositifs techniques visant \u00e0 affaiblir volontairement la s\u00e9curit\u00e9 des syst\u00e8mes d\u2019information et des communications \u00e9lectroniques tels que des cl\u00e9s de d\u00e9chiffrement ma\u00eetresses ou tout autre m\u00e9canisme permettant un acc\u00e8s non consenti aux donn\u00e9es prot\u00e9g\u00e9es \u00bb.<\/p>\n<p>Ce texte, qui transpose en droit fran\u00e7ais les directives europ\u00e9ennes NIS2, DORA et REC, devrait entrainer une hausse significative du niveau g\u00e9n\u00e9ral de cybers\u00e9curit\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/05\/Europe_1778076543567.jpg\" alt=\"\" width=\"140\" height=\"93\"><\/p>\n<h4><strong>\u0395\u03c5\u03c1\u03c9\u03c0\u03b1\u03ca\u03ba\u03ac \u03b8\u03b5\u03c3\u03bc\u03b9\u03ba\u03ac \u03cc\u03c1\u03b3\u03b1\u03bd\u03b1 \u03ba\u03b1\u03b9 \u03bf\u03c1\u03b3\u03b1\u03bd\u03b9\u03c3\u03bc\u03bf\u03af <\/strong><\/h4>\n<p>Le 10 septembre, Ursula von der Leyen a prononc\u00e9 un discours sur l&rsquo;\u00e9tat de l&rsquo;Union dans lequel elle a r\u00e9affirm\u00e9 que l&rsquo;Europe resterait souveraine dans la d\u00e9finition de ses propres r\u00e8gles et normes, repoussant ainsi les critiques transatlantiques.<\/p>\n<p>Le m\u00eame jour, 39 leaders et associations d\u2019industriels europ\u00e9ens ont sign\u00e9 la D\u00e9claration europ\u00e9enne sur l&rsquo;IA et la technologie, s&rsquo;engageant \u00e0 investir dans la souverainet\u00e9 technologique de l&rsquo;Europe.<\/p>\n<p>Mme von der Leyen a r\u00e9it\u00e9r\u00e9 les priorit\u00e9s cl\u00e9s de la strat\u00e9gie de l&rsquo;UE en mati\u00e8re d&rsquo;IA, notamment le futur r\u00e8glement sur le d\u00e9veloppement du cloud et de l&rsquo;IA, l&rsquo;initiative \u00ab Quantum Sandbox \u00bb et les investissements importants dans les \u00ab gigafactories \u00bb europ\u00e9ennes d&rsquo;IA.<\/p>\n<p>Le futur r\u00e8glement sur le d\u00e9veloppement du cloud et de l&rsquo;IA pourrait inclure des mesures de souverainet\u00e9 et de localisation des donn\u00e9es align\u00e9es sur la future strat\u00e9gie de l&rsquo;Union en mati\u00e8re de donn\u00e9es.<\/p>\n<p>La pr\u00e9sidente de la Commission a \u00e9galement soulign\u00e9 les objectifs de simplification de la r\u00e9glementation europ\u00e9enne, mettant en avant les r\u00e9centes propositions de r\u00e9forme susceptibles d&rsquo;avoir un impact sur la protection des donn\u00e9es, telles que la r\u00e9duction des obligations en mati\u00e8re de registre de donn\u00e9es et la rationalisation des exigences en mati\u00e8re de signalement des incidents dans la l\u00e9gislation num\u00e9rique.<\/p>\n<p>Enfin, elle a abord\u00e9 la question de la s\u00e9curit\u00e9 des enfants en ligne, annon\u00e7ant que la Commission solliciterait l&rsquo;avis d&rsquo;experts d&rsquo;ici la fin de l&rsquo;ann\u00e9e, s&rsquo;inspirant \u00e9ventuellement de l&rsquo;approche australienne en mati\u00e8re de restrictions sur les r\u00e9seaux sociaux.<\/p>\n<p>Le R\u00e8glement sur les donn\u00e9es (Data Act) est entr\u00e9 en vigueur le 12 septembre 2025.<\/p>\n<p>Ce texte donne aux utilisateurs de produits connect\u00e9s (entreprises ou particuliers qui poss\u00e8dent, louent ou louent \u00e0 bail un tel produit) un plus grand contr\u00f4le sur les donn\u00e9es qu&rsquo;ils g\u00e9n\u00e8rent, tout en maintenant des incitations pour ceux qui investissent dans les technologies de donn\u00e9es.<\/p>\n<p>Il d\u00e9finit \u00e9galement les conditions g\u00e9n\u00e9rales applicables aux situations dans lesquelles une entreprise a l&rsquo;obligation l\u00e9gale de partager des donn\u00e9es avec une autre entreprise.<\/p>\n<p>Le Comit\u00e9 europ\u00e9en de protection des donn\u00e9es a publi\u00e9 des lignes directrices sur l\u2019interaction entre le R\u00e8glement sur les services num\u00e9riques et le RGPD, soumises \u00e0 consultation publique jusqu\u2019\u00e0 fin octobre.<\/p>\n<p>Le Tribunal de l\u2019UE a condamn\u00e9 la Commission europ\u00e9enne \u00e0 payer 50 000 \u20ac de d\u00e9dommagement \u00e0 une personne mise en cause dans un communiqu\u00e9 de presse du Bureau anti-fraude europ\u00e9en (OLAF).<\/p>\n<p>Bien qu&rsquo;aucun nom n&rsquo;ait \u00e9t\u00e9 mentionn\u00e9 dans le communiqu\u00e9, des indices contextuels ont permis d&rsquo;identifier le chercheur. L&rsquo;affaire concern\u00e9e, <em>OC v Commission [C-479\/22 P]<\/em>, avait \u00e9t\u00e9 cit\u00e9e dans le r\u00e9cent recours EDPS c. SRB, qui suscite aujourd\u2019hui de vives r\u00e9actions concernant la port\u00e9e du caract\u00e8re identifiable des donn\u00e9es \u00e0 caract\u00e8re personnel.<\/p>\n<h4>&nbsp;<\/h4>\n<h4><strong>\u039d\u03ad\u03b1 \u03b1\u03c0\u03cc \u03c4\u03b9\u03c2 \u03c7\u03ce\u03c1\u03b5\u03c2 \u03bc\u03ad\u03bb\u03b7 \u03c4\u03b7\u03c2 \u0395\u03c5\u03c1\u03c9\u03c0\u03b1\u03ca\u03ba\u03ae\u03c2 \u0388\u03bd\u03c9\u03c3\u03b7\u03c2. <\/strong><\/h4>\n<p>En Allemagne, la Cour f\u00e9d\u00e9rale du travail a estim\u00e9 qu&rsquo;une entreprise avait ill\u00e9galement transf\u00e9r\u00e9 les donn\u00e9es personnelles de son employ\u00e9 \u00e0 sa soci\u00e9t\u00e9 m\u00e8re afin de tester un logiciel de gestion des ressources humaines.<\/p>\n<p>Ce transfert ne pouvait \u00eatre justifi\u00e9 par un int\u00e9r\u00eat l\u00e9gitime, car des donn\u00e9es fictives auraient suffi. La cour a accord\u00e9 \u00e0 l&#8217;employ\u00e9 200 \u20ac de dommages-int\u00e9r\u00eats pour pr\u00e9judice moral.<\/p>\n<p>En Autriche, un tribunal a estim\u00e9 que le droit d&rsquo;acc\u00e8s d&rsquo;une personne concern\u00e9e cesse \u00e0 son d\u00e9c\u00e8s et n&rsquo;est pas transf\u00e9r\u00e9 \u00e0 un successeur l\u00e9gal. Le tribunal a ainsi annul\u00e9 une d\u00e9cision de l&rsquo;autorit\u00e9 de protection des donn\u00e9es concernant une violation de droit d&rsquo;acc\u00e8s apr\u00e8s le d\u00e9c\u00e8s de la personne concern\u00e9e pendant la proc\u00e9dure d&rsquo;appel.<\/p>\n<p>L&rsquo;organisation autrichienne de d\u00e9fense des droits des consommateurs VSV a lanc\u00e9 une action collective contre Meta en Autriche et en Allemagne, r\u00e9clamant jusqu&rsquo;\u00e0 5 000 euros de dommages et int\u00e9r\u00eats pour les personnes \u00e2g\u00e9es de plus de 18 ans. Cette action concerne les outils professionnels de Meta, qui, selon VSV, sont utilis\u00e9s \u00e0 des fins de \u00ab surveillance ill\u00e9gale \u00bb de la vie priv\u00e9e des utilisateurs.<\/p>\n<p>L&rsquo;autorit\u00e9 de protection des donn\u00e9es belge a inflig\u00e9 une amende de 9 700 \u20ac au propri\u00e9taire d&rsquo;une maison d&rsquo;\u00e9tudiants pour avoir exploit\u00e9 ill\u00e9galement un syst\u00e8me de vid\u00e9osurveillance qui n&rsquo;\u00e9tait pas n\u00e9cessaire \u00e0 la protection de la propri\u00e9t\u00e9 ou au contr\u00f4le du respect du r\u00e8glement int\u00e9rieur et qui ne pouvait \u00eatre fond\u00e9 sur un int\u00e9r\u00eat l\u00e9gitime ou l&rsquo;ex\u00e9cution du contrat de location.<\/p>\n<p>L\u2019APD espagnole a impos\u00e9 une amende de 1 800 000 \u20ac \u00e0 une entreprise ayant trait\u00e9 sans base l\u00e9gale les donn\u00e9es \u00e0 caract\u00e8re personnel de travailleurs ind\u00e9pendants collect\u00e9es par une autorit\u00e9 publique.<\/p>\n<p>Elle a estim\u00e9 que, si l&rsquo;Agence espagnole des imp\u00f4ts (AEAT) \u00e9tait l\u00e9galement habilit\u00e9e \u00e0 communiquer certaines donn\u00e9es \u00e0 la Chambre de commerce, le transfert ult\u00e9rieur \u00e0 l\u2019entreprise Camerdata et l&rsquo;utilisation de ces donn\u00e9es \u00e0 des fins commerciales et marketing ne reposaient sur aucune base juridique valable.<\/p>\n<p>L&rsquo;int\u00e9r\u00eat l\u00e9gitime invoqu\u00e9 par l\u2019entreprise ne l&#8217;emportait pas sur les risques pour les droits et libert\u00e9s des travailleurs dont les donn\u00e9es avaient \u00e9t\u00e9 divulgu\u00e9es.<\/p>\n<p>En Estonie, la soci\u00e9t\u00e9 pharmaceutique Allium UPI s&rsquo;est vu infliger une amende de 3 000 000 \u20ac pour ne pas avoir mis en \u0153uvre les mesures techniques et organisationnelles ad\u00e9quates, telles que l\u2019authentification multifactorielle, ce qui a entra\u00een\u00e9 une violation de donn\u00e9es touchant 750 000 personnes, dont des enfants et des groupes vuln\u00e9rables.<\/p>\n<p>En Finlande, l\u2019APD a sanctionn\u00e9 une banque (S-Pankki Oyj) \u00e0 hauteur de 1 800 000 \u20ac pour ne pas avoir mis en \u0153uvre des mesures techniques et organisationnelles suffisantes concernant une nouvelle fonctionnalit\u00e9 de connexion sur son application, ce qui a conduit \u00e0 un acc\u00e8s non autoris\u00e9 par ses clients aux comptes d\u2019autres clients.<\/p>\n<p>L\u2019APD italienne a estim\u00e9 que la cliente d&rsquo;une entreprise avait le droit de r\u00e9voquer son consentement \u00e0 l&rsquo;utilisation de son image dans la publicit\u00e9 de l&rsquo;entreprise. Elle a pr\u00e9cis\u00e9 que le consentement pouvait \u00eatre r\u00e9voqu\u00e9 ind\u00e9pendamment des cons\u00e9quences \u00e9conomiques n\u00e9gatives pour le responsable du traitement.<\/p>\n<p>Avec un vote du S\u00e9nat le 17 septembre, l\u2019Italie devient le premier pays europ\u00e9en \u00e0 adopter une loi sur l\u2019IA.<\/p>\n<p>Apr\u00e8s avoir d\u00e9fini le cadre des principes g\u00e9n\u00e9raux, la loi accorde une attention particuli\u00e8re \u00e0 des secteurs cruciaux tels que le travail, la sant\u00e9 et la justice.<\/p>\n<p>Elle r\u00e9glemente \u00e9galement l&rsquo;utilisation de l&rsquo;IA par les mineurs et pr\u00e9voit des dispositions p\u00e9nales.<\/p>\n<p>L\u2019APD n\u00e9erlandaise m\u00e8ne actuellement une enqu\u00eate en collaboration avec les APDs italienne, luxembourgeoise et hongroise sur la mani\u00e8re dont les t\u00e9l\u00e9viseurs connect\u00e9s traitent les donn\u00e9es \u00e0 caract\u00e8re personnel.<\/p>\n<p>Le rapport constate notamment que les t\u00e9l\u00e9viseurs connect\u00e9s envoient une quantit\u00e9 importante de donn\u00e9es lors de leur installation, de leur utilisation quotidienne, lorsqu&rsquo;ils sont en veille et m\u00eame lorsqu&rsquo;ils sont \u00e9teints, et qu\u2019ils fonctionnent dans un \u00e9cosyst\u00e8me Internet opaque impliquant diff\u00e9rentes parties : fabricants, fournisseurs de syst\u00e8mes d&rsquo;exploitation, d\u00e9veloppeurs d&rsquo;applications, etc.<\/p>\n<p>Il souligne que les utilisateurs n&rsquo;ont souvent pas d&rsquo;autre choix que d&rsquo;accepter les politiques de confidentialit\u00e9 et ont des difficult\u00e9s \u00e0 identifier les responsables du traitement.<\/p>\n<p>Les applications pr\u00e9install\u00e9es (parfois impossibles \u00e0 supprimer) soul\u00e8vent des questions concernant la minimisation des donn\u00e9es et les droits des utilisateurs.<\/p>\n<p>Apr\u00e8s le lancement d\u2019Apertus IA, le chat open source suisse, un autre grand mod\u00e8le d&rsquo;apprentissage automatique open source soutenu par une institution publique en Europe est sorti, TildeOpen LLM.<\/p>\n<p>Il s\u2019agit d\u2019un mod\u00e8le linguistique fondamental con\u00e7u pour compenser les faiblesses des LLMs existants au regard des langues nordiques et est-europ\u00e9ennes, celles-ci \u00e9tant actuellement sous-repr\u00e9sent\u00e9es.<\/p>\n<p>Ce mod\u00e8le de 30 milliards de param\u00e8tres a \u00e9t\u00e9 d\u00e9velopp\u00e9 gr\u00e2ce \u00e0 un financement de la Commission europ\u00e9enne et entra\u00een\u00e9 sur le supercalculateur LUMI.<\/p>\n<p>Ces deux mod\u00e8les ont annonc\u00e9 se confirmer au r\u00e8glement europ\u00e9en sur l\u2019IA.<\/p>\n<h4><strong>&nbsp;<\/strong><\/h4>\n<h4><strong><img decoding=\"async\" src=\"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/05\/INTERNATIO_1778076937363.jpg\" alt=\"\" width=\"150\" height=\"85\">&nbsp;<\/strong><\/h4>\n<p>La 47e \u00e9dition de l\u2019assembl\u00e9e g\u00e9n\u00e9rale de la protection de la vie priv\u00e9e, qui s&rsquo;est tenue en septembre dernier \u00e0 S\u00e9oul, a r\u00e9affirm\u00e9 que la confidentialit\u00e9 et la s\u00e9curit\u00e9 des donn\u00e9es sont des enjeux cruciaux auxquels le monde est confront\u00e9 aujourd&rsquo;hui.<\/p>\n<p>L\u2019\u00e9v\u00e9nement annuel r\u00e9unit les r\u00e9gulateurs ainsi que des entreprises et organisations du monde entier.<\/p>\n<p>Vingt autorit\u00e9s de protection des donn\u00e9es ont adopt\u00e9 \u00e0 cette occasion une d\u00e9claration commune afin de construire un cadre de gouvernance fiable pour une IA digne de confiance.<\/p>\n<p>Elles pr\u00e9conisent l\u2019int\u00e9gration des principes de protection des donn\u00e9es d\u00e8s la conception, la mise en place d\u2019une gouvernance solide des donn\u00e9es et l\u2019anticipation de la gestion des risques.<\/p>\n<p>La d\u00e9claration souligne \u00e9galement la complexit\u00e9 croissante du traitement des donn\u00e9es dans ce contexte et souligne la diversit\u00e9 des acteurs impliqu\u00e9s, ainsi que la n\u00e9cessit\u00e9 d&rsquo;un cadre r\u00e9glementaire adapt\u00e9 aux progr\u00e8s technologiques.<\/p>\n<p>Aux Etats-Unis, le \u00ab Shutodwn \u00bb a des cons\u00e9quences non n\u00e9gligeables en mati\u00e8re de protection des donn\u00e9es.<\/p>\n<p>Certaines agences f\u00e9d\u00e9rales sont presque enti\u00e8rement ferm\u00e9es, notamment la Commission f\u00e9d\u00e9rale du commerce (FTC), l&rsquo;organisme principal charg\u00e9 de faire respecter la confidentialit\u00e9 des donn\u00e9es.<\/p>\n<p>Au sein de la FTC, c&rsquo;est le Bureau de la protection des consommateurs qui est le plus touch\u00e9 par les cong\u00e9s forc\u00e9s.<\/p>\n<p>Sauf dans les cas o\u00f9 les pr\u00e9judices sont jug\u00e9s extr\u00eamement graves, les questions relatives \u00e0 la protection des consommateurs seront suspendues, qu&rsquo;il s&rsquo;agisse d&rsquo;enqu\u00eates pr\u00e9liminaires, de proc\u00e9dures administratives ou de poursuites devant les tribunaux f\u00e9d\u00e9raux.<\/p>\n<p>Les utilisateurs am\u00e9ricains de ChatGPT Plus, Pro et Free peuvent d\u00e9sormais acheter directement aupr\u00e8s de la plateforme de vente Etsy, et de nombreux autres vendeurs seront bient\u00f4t accessibles \u00e9galement.<\/p>\n<p>Ceci implique, pour ChatGPT comme pour les autres syst\u00e8mes d&rsquo;IA agentique, que l\u2019utilisateur donne acc\u00e8s \u00e0 des tiers \u00e0 ses informations personnelles, et en particulier bancaires, avec toutes les questions de vuln\u00e9rabilit\u00e9 de donn\u00e9es que cela suppose.<\/p>","protected":false},"excerpt":{"rendered":"<p>Veille Juridique n\u00b087 \u2013 septembre 2025.&nbsp; &nbsp; Cinq ans apr\u00e8s le Brexit : \u00e9tat des lieux au Royaume-Uni. Depuis la sortie du Royaume-Uni de l\u2019Union europ\u00e9enne, le droit britannique de la protection des donn\u00e9es s\u2019\u00e9loigne lentement mais s\u00fbrement du cadre r\u00e9glementaire europ\u00e9en. S\u2019il y a une tendance de part et d\u2019autre de la Manche \u00e0 [&hellip;]<\/p>","protected":false},"author":1,"featured_media":14095,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[35],"tags":[],"class_list":["post-14099","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veille-juridique"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cinq ans apr\u00e8s le Brexit : \u00e9tat des lieux au Royaume-Uni - Viqtor<\/title>\n<meta name=\"description\" content=\"Cinq ans apr\u00e8s le Brexit : \u00e9tat des lieux au Royaume-Uni - Viqtor\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/viqtor.eu\/el\/cinq-ans-apres-le-brexit-etat-des-lieux-au-royaume-uni\/\" \/>\n<meta property=\"og:locale\" content=\"el_GR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cinq ans apr\u00e8s le Brexit : \u00e9tat des lieux au Royaume-Uni - Viqtor\" \/>\n<meta property=\"og:description\" content=\"Cinq ans apr\u00e8s le Brexit : \u00e9tat des lieux au Royaume-Uni - Viqtor\" \/>\n<meta property=\"og:url\" content=\"https:\/\/viqtor.eu\/el\/cinq-ans-apres-le-brexit-etat-des-lieux-au-royaume-uni\/\" \/>\n<meta property=\"og:site_name\" content=\"Viqtor\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T07:40:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/04\/widget-viqtor.png\" \/>\n<meta name=\"author\" content=\"Bruno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u03a3\u03c5\u03bd\u03c4\u03ac\u03c7\u03b8\u03b7\u03ba\u03b5 \u03b1\u03c0\u03cc\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bruno\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u0395\u03ba\u03c4\u03b9\u03bc\u03ce\u03bc\u03b5\u03bd\u03bf\u03c2 \u03c7\u03c1\u03cc\u03bd\u03bf\u03c2 \u03b1\u03bd\u03ac\u03b3\u03bd\u03c9\u03c3\u03b7\u03c2\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 \u03bb\u03b5\u03c0\u03c4\u03ac\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/viqtor.eu\/cinq-ans-apres-le-brexit-etat-des-lieux-au-royaume-uni\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/viqtor.eu\/cinq-ans-apres-le-brexit-etat-des-lieux-au-royaume-uni\/\"},\"author\":{\"name\":\"Bruno\",\"@id\":\"https:\/\/viqtor.eu\/#\/schema\/person\/3dbd9cc82a28f6cf1695c92eda0099ad\"},\"headline\":\"Cinq ans apr\u00e8s le Brexit : \u00e9tat des lieux au Royaume-Uni\",\"datePublished\":\"2026-05-13T07:40:05+00:00\",\"dateModified\":\"2026-05-13T07:40:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/viqtor.eu\/cinq-ans-apres-le-brexit-etat-des-lieux-au-royaume-uni\/\"},\"wordCount\":3179,\"publisher\":{\"@id\":\"https:\/\/viqtor.eu\/#organization\"},\"image\":{\"@id\":\"https:\/\/viqtor.eu\/cinq-ans-apres-le-brexit-etat-des-lieux-au-royaume-uni\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/05\/0238ce31-b132-4bb8-8a04-b8b71efd131c_1778075352676.jpg\",\"articleSection\":[\"Veille juridique\"],\"inLanguage\":\"el\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/viqtor.eu\/cinq-ans-apres-le-brexit-etat-des-lieux-au-royaume-uni\/\",\"url\":\"https:\/\/viqtor.eu\/cinq-ans-apres-le-brexit-etat-des-lieux-au-royaume-uni\/\",\"name\":\"Cinq ans apr\u00e8s le Brexit : \u00e9tat des lieux au Royaume-Uni - Viqtor\",\"isPartOf\":{\"@id\":\"https:\/\/viqtor.eu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/viqtor.eu\/cinq-ans-apres-le-brexit-etat-des-lieux-au-royaume-uni\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/viqtor.eu\/cinq-ans-apres-le-brexit-etat-des-lieux-au-royaume-uni\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/05\/0238ce31-b132-4bb8-8a04-b8b71efd131c_1778075352676.jpg\",\"datePublished\":\"2026-05-13T07:40:05+00:00\",\"dateModified\":\"2026-05-13T07:40:05+00:00\",\"description\":\"Cinq ans apr\u00e8s le Brexit : \u00e9tat des lieux au Royaume-Uni - Viqtor\",\"breadcrumb\":{\"@id\":\"https:\/\/viqtor.eu\/cinq-ans-apres-le-brexit-etat-des-lieux-au-royaume-uni\/#breadcrumb\"},\"inLanguage\":\"el\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/viqtor.eu\/cinq-ans-apres-le-brexit-etat-des-lieux-au-royaume-uni\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"el\",\"@id\":\"https:\/\/viqtor.eu\/cinq-ans-apres-le-brexit-etat-des-lieux-au-royaume-uni\/#primaryimage\",\"url\":\"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/05\/0238ce31-b132-4bb8-8a04-b8b71efd131c_1778075352676.jpg\",\"contentUrl\":\"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/05\/0238ce31-b132-4bb8-8a04-b8b71efd131c_1778075352676.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/viqtor.eu\/cinq-ans-apres-le-brexit-etat-des-lieux-au-royaume-uni\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/viqtor.eu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cinq ans apr\u00e8s le Brexit : \u00e9tat des lieux au Royaume-Uni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/viqtor.eu\/#website\",\"url\":\"https:\/\/viqtor.eu\/\",\"name\":\"Viqtor\",\"description\":\"Faites du RGPD une opportunit\u00e9 pour votre entreprise.\",\"publisher\":{\"@id\":\"https:\/\/viqtor.eu\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/viqtor.eu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"el\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/viqtor.eu\/#organization\",\"name\":\"viqtor.eu\",\"url\":\"https:\/\/viqtor.eu\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"el\",\"@id\":\"https:\/\/viqtor.eu\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/viqtor.eu\/wp-content\/uploads\/2023\/06\/favicon-noir.svg\",\"contentUrl\":\"https:\/\/viqtor.eu\/wp-content\/uploads\/2023\/06\/favicon-noir.svg\",\"width\":108,\"height\":86,\"caption\":\"viqtor.eu\"},\"image\":{\"@id\":\"https:\/\/viqtor.eu\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/viqtor.eu\/#\/schema\/person\/3dbd9cc82a28f6cf1695c92eda0099ad\",\"name\":\"Bruno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"el\",\"@id\":\"https:\/\/viqtor.eu\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e5a596f9489de15bfe046e97fb771f63589b601ca7e81ccc2bb9a23582f441a3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e5a596f9489de15bfe046e97fb771f63589b601ca7e81ccc2bb9a23582f441a3?s=96&d=mm&r=g\",\"caption\":\"Bruno\"},\"sameAs\":[\"https:\/\/exciting-panini.13-37-234-21.plesk.page\"],\"url\":\"https:\/\/viqtor.eu\/el\/author\/mouad_zxum2ebi\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cinq ans apr\u00e8s le Brexit : \u00e9tat des lieux au Royaume-Uni - Viqtor","description":"Cinq ans apr\u00e8s le Brexit : \u00e9tat des lieux au Royaume-Uni - Viqtor","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/viqtor.eu\/el\/cinq-ans-apres-le-brexit-etat-des-lieux-au-royaume-uni\/","og_locale":"el_GR","og_type":"article","og_title":"Cinq ans apr\u00e8s le Brexit : \u00e9tat des lieux au Royaume-Uni - Viqtor","og_description":"Cinq ans apr\u00e8s le Brexit : \u00e9tat des lieux au Royaume-Uni - Viqtor","og_url":"https:\/\/viqtor.eu\/el\/cinq-ans-apres-le-brexit-etat-des-lieux-au-royaume-uni\/","og_site_name":"Viqtor","article_published_time":"2026-05-13T07:40:05+00:00","og_image":[{"url":"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/04\/widget-viqtor.png"}],"author":"Bruno","twitter_card":"summary_large_image","twitter_misc":{"\u03a3\u03c5\u03bd\u03c4\u03ac\u03c7\u03b8\u03b7\u03ba\u03b5 \u03b1\u03c0\u03cc":"Bruno","\u0395\u03ba\u03c4\u03b9\u03bc\u03ce\u03bc\u03b5\u03bd\u03bf\u03c2 \u03c7\u03c1\u03cc\u03bd\u03bf\u03c2 \u03b1\u03bd\u03ac\u03b3\u03bd\u03c9\u03c3\u03b7\u03c2":"16 \u03bb\u03b5\u03c0\u03c4\u03ac"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/viqtor.eu\/cinq-ans-apres-le-brexit-etat-des-lieux-au-royaume-uni\/#article","isPartOf":{"@id":"https:\/\/viqtor.eu\/cinq-ans-apres-le-brexit-etat-des-lieux-au-royaume-uni\/"},"author":{"name":"Bruno","@id":"https:\/\/viqtor.eu\/#\/schema\/person\/3dbd9cc82a28f6cf1695c92eda0099ad"},"headline":"Cinq ans apr\u00e8s le Brexit : \u00e9tat des lieux au Royaume-Uni","datePublished":"2026-05-13T07:40:05+00:00","dateModified":"2026-05-13T07:40:05+00:00","mainEntityOfPage":{"@id":"https:\/\/viqtor.eu\/cinq-ans-apres-le-brexit-etat-des-lieux-au-royaume-uni\/"},"wordCount":3179,"publisher":{"@id":"https:\/\/viqtor.eu\/#organization"},"image":{"@id":"https:\/\/viqtor.eu\/cinq-ans-apres-le-brexit-etat-des-lieux-au-royaume-uni\/#primaryimage"},"thumbnailUrl":"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/05\/0238ce31-b132-4bb8-8a04-b8b71efd131c_1778075352676.jpg","articleSection":["Veille juridique"],"inLanguage":"el"},{"@type":"WebPage","@id":"https:\/\/viqtor.eu\/cinq-ans-apres-le-brexit-etat-des-lieux-au-royaume-uni\/","url":"https:\/\/viqtor.eu\/cinq-ans-apres-le-brexit-etat-des-lieux-au-royaume-uni\/","name":"Cinq ans apr\u00e8s le Brexit : \u00e9tat des lieux au Royaume-Uni - Viqtor","isPartOf":{"@id":"https:\/\/viqtor.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/viqtor.eu\/cinq-ans-apres-le-brexit-etat-des-lieux-au-royaume-uni\/#primaryimage"},"image":{"@id":"https:\/\/viqtor.eu\/cinq-ans-apres-le-brexit-etat-des-lieux-au-royaume-uni\/#primaryimage"},"thumbnailUrl":"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/05\/0238ce31-b132-4bb8-8a04-b8b71efd131c_1778075352676.jpg","datePublished":"2026-05-13T07:40:05+00:00","dateModified":"2026-05-13T07:40:05+00:00","description":"Cinq ans apr\u00e8s le Brexit : \u00e9tat des lieux au Royaume-Uni - Viqtor","breadcrumb":{"@id":"https:\/\/viqtor.eu\/cinq-ans-apres-le-brexit-etat-des-lieux-au-royaume-uni\/#breadcrumb"},"inLanguage":"el","potentialAction":[{"@type":"ReadAction","target":["https:\/\/viqtor.eu\/cinq-ans-apres-le-brexit-etat-des-lieux-au-royaume-uni\/"]}]},{"@type":"ImageObject","inLanguage":"el","@id":"https:\/\/viqtor.eu\/cinq-ans-apres-le-brexit-etat-des-lieux-au-royaume-uni\/#primaryimage","url":"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/05\/0238ce31-b132-4bb8-8a04-b8b71efd131c_1778075352676.jpg","contentUrl":"https:\/\/viqtor.eu\/wp-content\/uploads\/2026\/05\/0238ce31-b132-4bb8-8a04-b8b71efd131c_1778075352676.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/viqtor.eu\/cinq-ans-apres-le-brexit-etat-des-lieux-au-royaume-uni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/viqtor.eu\/"},{"@type":"ListItem","position":2,"name":"Cinq ans apr\u00e8s le Brexit : \u00e9tat des lieux au Royaume-Uni"}]},{"@type":"WebSite","@id":"https:\/\/viqtor.eu\/#website","url":"https:\/\/viqtor.eu\/","name":"Viqtor","description":"Faites du RGPD une opportunit\u00e9 pour votre entreprise.","publisher":{"@id":"https:\/\/viqtor.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/viqtor.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"el"},{"@type":"Organization","@id":"https:\/\/viqtor.eu\/#organization","name":"viqtor.eu","url":"https:\/\/viqtor.eu\/","logo":{"@type":"ImageObject","inLanguage":"el","@id":"https:\/\/viqtor.eu\/#\/schema\/logo\/image\/","url":"https:\/\/viqtor.eu\/wp-content\/uploads\/2023\/06\/favicon-noir.svg","contentUrl":"https:\/\/viqtor.eu\/wp-content\/uploads\/2023\/06\/favicon-noir.svg","width":108,"height":86,"caption":"viqtor.eu"},"image":{"@id":"https:\/\/viqtor.eu\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/viqtor.eu\/#\/schema\/person\/3dbd9cc82a28f6cf1695c92eda0099ad","name":"Bruno","image":{"@type":"ImageObject","inLanguage":"el","@id":"https:\/\/viqtor.eu\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e5a596f9489de15bfe046e97fb771f63589b601ca7e81ccc2bb9a23582f441a3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e5a596f9489de15bfe046e97fb771f63589b601ca7e81ccc2bb9a23582f441a3?s=96&d=mm&r=g","caption":"Bruno"},"sameAs":["https:\/\/exciting-panini.13-37-234-21.plesk.page"],"url":"https:\/\/viqtor.eu\/el\/author\/mouad_zxum2ebi\/"}]}},"_links":{"self":[{"href":"https:\/\/viqtor.eu\/el\/wp-json\/wp\/v2\/posts\/14099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/viqtor.eu\/el\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/viqtor.eu\/el\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/viqtor.eu\/el\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/viqtor.eu\/el\/wp-json\/wp\/v2\/comments?post=14099"}],"version-history":[{"count":0,"href":"https:\/\/viqtor.eu\/el\/wp-json\/wp\/v2\/posts\/14099\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/viqtor.eu\/el\/wp-json\/wp\/v2\/media\/14095"}],"wp:attachment":[{"href":"https:\/\/viqtor.eu\/el\/wp-json\/wp\/v2\/media?parent=14099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/viqtor.eu\/el\/wp-json\/wp\/v2\/categories?post=14099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/viqtor.eu\/el\/wp-json\/wp\/v2\/tags?post=14099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}